{"id":3009,"date":"2025-09-14T09:30:41","date_gmt":"2025-09-14T09:30:41","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=3009"},"modified":"2025-09-14T09:30:50","modified_gmt":"2025-09-14T09:30:50","slug":"14-a-21-de-setembro","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2025\/09\/14\/14-a-21-de-setembro\/","title":{"rendered":"14 a 21 de Setembro"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Informa\u00e7\u00f5es<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Na Segunda-feira, dia (15\/09) haver\u00e1:\n<ul class=\"wp-block-list\">\n<li>Eucaristia na Igreja Paroquial, \u00e0s 19:00;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Na Quarta-feira, dia (17\/09) haver\u00e1:\n<ul class=\"wp-block-list\">\n<li>Eucaristia nas Quintas do Norte, \u00e0s 20:00; <\/li>\n\n\n\n<li>Reuni\u00e3o do Conselho Econ\u00f3mico, \u00e0s 21:15;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Na Quinta-feira, dia (18\/09) haver\u00e1:\n<ul class=\"wp-block-list\">\n<li>Reuni\u00e3o do Conselho Pastoral e Paroquial, \u00e0s 21:30;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Na Sexta-feira, dia (19\/09) haver\u00e1:\n<ul class=\"wp-block-list\">\n<li>Atendimento Paroquial, das 16:00 \u00e0s 17:30;<\/li>\n\n\n\n<li><span style=\"color: initial;\">Eucaristia na Igreja Paroquial, \u00e0s 19:00;<\/span><\/li>\n\n\n\n<li>Noite de Fados na Assembleia de Teatro da Torreira, \u00e0s 21:00, com direito a uma bebida e petiscos;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No S\u00e1bado, dia (20\/09) haver\u00e1:<ul><li>Inscri\u00e7\u00f5es de Catequese para todos os grupos, a partir das 14:30;<\/li><\/ul><ul><li>Eucaristia na Igreja Matriz, \u00e0s 19:00;<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Reuni\u00e3o de Prepara\u00e7\u00e3o para Crisma de Adultos, \u00e0s 21:00;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No Domingo, dia (21\/09) haver\u00e1:<ul><li>Eucaristia nas Quintas do Norte, \u00e0s 8:00;<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Eucaristia na Igreja Paroquial, \u00e0s 11:00;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A venda dos Bolos no fim de semana passado na igreja da Torreira esteve ao cuidado do grupo de Catequistas, no s\u00e1bado o valor foi de 131\u20ac e no domingo o valor foi de 80\u20ac e nas Quintas do Norte esteve ao cuidado do Grupo das Zeladoras e o valor de 57\u20ac.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No pr\u00f3ximo s\u00e1bado, dia 20 de setembro est\u00e1 agendado as inscri\u00e7\u00f5es para todos os grupos de catequese de 2025\/2026 a partir das 14:30 na igreja da Torreira.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No dia 4 de outubro haver\u00e1 o passeio com todos os Agentes de Pastoral das par\u00f3quias de Torreira e S\u00e3o Jacinto, Conselhos Econ\u00f3micos e Pastorais, Catequistas, Leitores, Ac\u00f3litos, Ministros Extraordin\u00e1rios da Comunh\u00e3o, Zeladores. Os interessados devem inscrever-se para organizar o transporte.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No dia 27 de setembro ser\u00e1 celebrado o jubileu (75 anos) da chegada do Movimento Apost\u00f3lico de Schoenstatt a Portugal. O local de concentra\u00e7\u00e3o ser\u00e1 no Santu\u00e1rio das Colonias (\u00cdlhavo) a Eucaristia ser\u00e1, \u00e0s 17 horas presidida pelo Padre Gon\u00e7alo Cravo. Estamos convidados para este momento de festa e de fam\u00edlia com as irm\u00e3s de Schoenstatt.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"intencoes-de-missa\">Inten\u00e7\u00f5es de Missa<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"segunda-feira-21-igreja-matriz-19-00h\"><strong>Segunda-feira, 15 \u2013\u00a0Igreja Matriz, 19:00h<\/strong><\/h3>\n\n\n\n<p>+ Maria Augusta da Silva Acabou.<br>+ Rosa do Ros\u00e1rio Silva Vieira e Carlos Silva Vieira.<br>+ Benvinda das Flores da Silva Amaral.<br>+ Paulo Jorge da Silva Mala e familiares.<br>+ Domingos Maria Evaristo, esposa e filha.<br>+ M\u00e1rio da Cunha, Eug\u00e9nia Marques da Silva e Manuel Amaro da Cunha.<br>+ Abel Barbosa, Manuel Jo\u00e3o Barbosa, Ezequiel Barbosa e Maria Jos\u00e9 Evaristo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"quarta-feira-23-quintas-do-norte-20-00h\"><strong>Quarta-feira, 17 \u2013\u00a0Quintas do Norte, 20:00h<\/strong><\/h3>\n\n\n\n<p><a>+ <\/a>Arlindo Marques de Oliveira.<br>+ Manuel Rebelo, Rosa Em\u00edlia e familiares.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"sexta-feira-25-igreja-matriz-19-00h\"><strong>Sexta-feira, 19 \u2013\u00a0\u00a0Igreja Matriz, 19:00h<\/strong><\/h3>\n\n\n\n<p>+ Paulo S\u00e9rgio Ribeiro Ferreira.<br>+ Manuel da Silva Bastos.<br>+ Maria do Ros\u00e1rio e Jos\u00e9 Ramos.<br>+ Pelas Almas do Purgat\u00f3rio.<\/p>\n\n\n\n<div style=\"height:54px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informa\u00e7\u00f5es Inten\u00e7\u00f5es de Missa Segunda-feira, 15 \u2013\u00a0Igreja Matriz, 19:00h + Maria Augusta da Silva Acabou.+ Rosa do Ros\u00e1rio Silva Vieira e Carlos Silva Vieira.+ Benvinda das Flores da Silva Amaral.+ Paulo Jorge da Silva Mala e familiares.+ Domingos Maria Evaristo, &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2025\/09\/14\/14-a-21-de-setembro\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[9,31],"tags":[30],"class_list":["post-3009","post","type-post","status-publish","format-standard","hentry","category-informacao","category-intencoes","tag-informacao-semanal"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/3009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=3009"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/3009\/revisions"}],"predecessor-version":[{"id":3010,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/3009\/revisions\/3010"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=3009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=3009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=3009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}