{"id":2724,"date":"2025-02-02T10:07:29","date_gmt":"2025-02-02T10:07:29","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=2724"},"modified":"2025-02-02T10:07:33","modified_gmt":"2025-02-02T10:07:33","slug":"novos-ventos-02-de-fevereiro","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2025\/02\/02\/novos-ventos-02-de-fevereiro\/","title":{"rendered":"Novos Ventos &#8211; 02 de Fevereiro"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"vii-domingo-do-tempo-comum-ano-c\">Apresenta\u00e7\u00e3o do Senhor\u00a0\u2013 Ano C<br>Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto<\/h2>\n\n\n\n<p>Neste Domingo celebramos a Festa da Apresenta\u00e7\u00e3o do Senhor. Conforme era costume na Tradi\u00e7\u00e3o Judaica todo o filho primog\u00e9nito var\u00e3o era consagrado ao Senhor. Assim, sucedeu tamb\u00e9m com a Fam\u00edlia de Nazar\u00e9, Jos\u00e9 e Maria levam o Menino ao templo, a fim de ser oferecido ao Senhor. Este gesto de Maria que \u00aboferece\u00bb, traduz-se num gesto lit\u00fargico quando ao celebrarmos a Eucaristia, oferecemos os frutos da terra, oferecemos os nossos trabalhos e que ser\u00e3o colocados sobre o altar, como s\u00edmbolo da nossa vida. Esta festa da Apresenta\u00e7\u00e3o do Senhor revela aquilo que ser\u00e1 o acontecimento da Paix\u00e3o. Nessa altura encontrava-se no templo Sime\u00e3o e Ana, o Senhor tinha revelado que n\u00e3o haveriam de morrer antes de ver o Messias e foram ao templo movidos pelo Esp\u00edrito, Sime\u00e3o recebeu o Menino nos bra\u00e7os e bendisse a Deus, depois come\u00e7ou a profetizar acerca do Menino dizendo: \u00abEste Menino foi estabelecido para que muitos caiam ou se levantem em Israel e para ser sinal de contradi\u00e7\u00e3o; \u2013 e uma espada trespassar\u00e1 a tua alma assim se revelar\u00e3o os pensamentos de todos os cora\u00e7\u00f5es\u00bb. A M\u00e3e de Jesus n\u00e3o compreende aquela profecia, mas guarda as palavras no Seu cora\u00e7\u00e3o, Maria n\u00e3o entende que aquela espada de dor seria o momento da Paix\u00e3o.<\/p>\n\n\n\n<p><strong>A leitura da Profecia de Malaquias,<\/strong> o profeta Malaquias anuncia a proximidade do \u201cDia do Senhor\u201d, o dia em que Deus vai entrar no seu Templo para purificar o seu povo, para lhe renovar o cora\u00e7\u00e3o e para o capacitar para viver num dinamismo novo. Come\u00e7ar\u00e1 nesse dia um tempo novo, o tempo da nova Alian\u00e7a entre Deus e os homens.<\/p>\n\n\n\n<p><strong>A leitura da Ep\u00edstola aos Hebreus,<\/strong>&nbsp;um catequista crist\u00e3o, escrevendo \u201caos Hebreus\u201d, apresenta Jesus como o irm\u00e3o dos homens, que veio ao mundo para promover os \u201cdescendentes de Abra\u00e3o\u201d \u00e0 categoria de Filhos amados de Deus. Oferecendo a sua vida por amor, ele introduziu na nossa d\u00e9bil, fr\u00e1gil e pecadora natureza humana, dinamismos de supera\u00e7\u00e3o dos nossos limites, dinamismos de vida nova, de vida verdadeira e eterna.<\/p>\n\n\n\n<p><strong>O Evangelho de Nosso Senhor Jesus Cristo Segundo S\u00e3o Lucas, <\/strong>o evangelista<strong> <\/strong>Lucas mostra como Jesus, poucos dias ap\u00f3s o seu nascimento, entrou no Templo de Jerusal\u00e9m para concretizar a promessa outrora feita por Deus atrav\u00e9s do profeta Malaquias. Recebido por Sime\u00e3o e Ana, representantes do Israel fiel que esperava ansiosamente o Messias de Deus, Jesus \u00e9 apresentado como \u201cluz para as na\u00e7\u00f5es\u201d e \u201cgl\u00f3ria de Israel\u201d. Ele traz ao mundo a salva\u00e7\u00e3o de Deus.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><u>Evangelho de Nosso Senhor Jesus Cristo Segundo S\u00e3o Lucas<\/u><\/strong><\/h3>\n\n\n\n<p>Ao chegarem os dias da purifica\u00e7\u00e3o, segundo a Lei de Mois\u00e9s, Maria e Jos\u00e9 levaram Jesus a Jerusal\u00e9m, para O apresentarem ao Senhor, como est\u00e1 escrito na Lei do Senhor: \u00abTodo o filho primog\u00e9nito var\u00e3o ser\u00e1 consagrado ao Senhor\u00bb, e para oferecerem em sacrif\u00edcio um par de rolas ou duas pombinhas, como se diz na Lei do Senhor. Vivia em Jerusal\u00e9m um homem chamado Sime\u00e3o, homem justo e piedoso, que esperava a consola\u00e7\u00e3o de Israel; e o Esp\u00edrito Santo estava nele. O Esp\u00edrito Santo revelara-lhe que n\u00e3o morreria antes de ver o Messias do Senhor; e veio ao templo, movido pelo Esp\u00edrito. Quando os pais de Jesus trouxeram o Menino para cumprirem as prescri\u00e7\u00f5es da Lei no que lhes dizia respeito, Sime\u00e3o recebeu-O em seus bra\u00e7os e bendisse a Deus, exclamando: \u00abAgora, Senhor, segundo a vossa palavra, deixareis ir em paz o vosso servo, porque os meus olhos viram a vossa salva\u00e7\u00e3o, que pusestes ao alcance de todos os povos: luz para se revelar \u00e0s na\u00e7\u00f5es e gl\u00f3ria de Israel, vosso povo\u00bb. O pai e a m\u00e3e do Menino Jesus estavam admirados com o que d\u2019Ele se dizia. Sime\u00e3o aben\u00e7oou-os e disse a Maria, sua M\u00e3e: \u00abEste Menino foi estabelecido para que muitos caiam ou se levantem em Israel e para ser sinal de contradi\u00e7\u00e3o; \u2013 e uma espada trespassar\u00e1 a tua alma assim se revelar\u00e3o os pensamentos de todos os cora\u00e7\u00f5es\u00bb. Havia tamb\u00e9m uma profetiza, Ana, filha de Fanuel, da tribo de Aser. Era de idade muito avan\u00e7ada e tinha vivido casada sete anos ap\u00f3s o tempo de donzela e vi\u00fava at\u00e9 aos oitenta e quatro. N\u00e3o se afastava do templo, servindo a Deus noite e dia, com jejuns e ora\u00e7\u00f5es. Estando presente na mesma ocasi\u00e3o, come\u00e7ou tamb\u00e9m a louvar a Deus e a falar acerca do Menino a todos os que esperavam a liberta\u00e7\u00e3o de Jerusal\u00e9m. Cumpridas todas as prescri\u00e7\u00f5es da Lei do Senhor, voltaram para a Galileia, para a sua cidade de Nazar\u00e9. Entretanto, o Menino crescia e tornava-Se robusto, enchendo-Se de sabedoria. E a gra\u00e7a de Deus estava com Ele. \u00a0<br><strong>Palavra da Salva\u00e7\u00e3o<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"672\" height=\"454\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/22.jpg\" alt=\"\" class=\"wp-image-2725\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/22.jpg 672w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/22-300x203.jpg 300w\" sizes=\"(max-width: 672px) 100vw, 672px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><u>Nicar\u00e1gua, mais de 30 monjas Clarissas s\u00e3o expulsas de tr\u00eas mosteiros<\/u><\/strong><\/h3>\n\n\n\n<p>Mais de 30 monjas da Ordem de Santa Clara, conhecidas como Clarissas, foram levadas dos tr\u00eas mosteiros nicaraguenses de Man\u00e1gua, Matagalpa e Chinandega na noite de 28 para 29 de janeiro.<\/p>\n\n\n\n<p><strong>Religiosas expulsas do pa\u00eds<\/strong><\/p>\n\n\n\n<p>Em maio de 2023, as autoridades de Man\u00e1gua dissolveram a Associa\u00e7\u00e3o das Irm\u00e3s Clarissas Franciscanas e nove outras realidades e organiza\u00e7\u00f5es. V\u00e1rias congrega\u00e7\u00f5es religiosas de irm\u00e3s foram parcial ou totalmente expulsas da Nicar\u00e1gua nos \u00faltimos anos, em particular ap\u00f3s as pol\u00eamicas consultas em novembro de 2021, nas quais Daniel Ortega foi reeleito para um quinto mandato, o quarto consecutivo.<\/p>\n\n\n\n<p><strong>Repress\u00e3o contra ONGs<\/strong><\/p>\n\n\n\n<p>Medidas semelhantes tamb\u00e9m foram tomadas nas \u00faltimas horas. De fato, o governo nicaraguense cancelou o status legal de 10 outras associa\u00e7\u00f5es que operavam como organiza\u00e7\u00f5es sem fins lucrativos, elevando o n\u00famero total de ONGs proibidas desde dezembro de 2018 no pa\u00eds centro-americano para mais de 5.600<strong><u><\/u><\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"750\" height=\"422\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/23.jpg\" alt=\"\" class=\"wp-image-2726\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/23.jpg 750w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/23-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><u>Igreja\/Portugal: \u00abO mundo precisa de uma terapia do amor\u00bb \u2013 D. Ant\u00f3nio Moiteiro<\/u><\/strong><\/h3>\n\n\n\n<p>\u201cComunica\u00e7\u00e3o da f\u00e9 em tempos de mudan\u00e7a\u201d foi o tema que envolveu tr\u00eas dias, 28, 29 e 30 deste m\u00eas, em F\u00e1tima, as jornadas do clero das dioceses do centro do pa\u00eds (Aveiro, Coimbra, Guarda, Leiria-F\u00e1tima, Portalegre-Castelo Branco e Viseu).<\/p>\n\n\n\n<p>Jo\u00e3o Duque, professor da Universidade Cat\u00f3lica Portuguesa (UCP) abriu a perspetiva do p\u00f3s cristianismo e indicou a necessidade de \u201cpensar o cristianismo de outro modo, desconstruindo algumas constru\u00e7\u00f5es\u201d e, ao falar da linguagem e do simbolismo, apontou desafios pessoais e institucionais do cristianismo. O docente apontou que \u201cN\u00e3o h\u00e1 uma \u00fanica forma de ser crist\u00e3o\u201d e questionou \u201ca rela\u00e7\u00e3o do crist\u00e3o n\u00e3o praticante com as par\u00f3quias\u201d. \u201cJesus pregava aos membros de uma multid\u00e3o, que n\u00e3o tinham as caracter\u00edsticas do crist\u00e3o comprometido; n\u00e3o teremos de rever este estatuto? O crist\u00e3o n\u00e3o praticante n\u00e3o poder\u00e1 beber do cristianismo na sociedade? Que rela\u00e7\u00e3o h\u00e1 nas par\u00f3quias com estes crist\u00e3os n\u00e3o praticantes?\u201d<\/p>\n\n\n\n<p>A tarde foi preenchida com quatro ateliers: Margarida Cordo, Psic\u00f3loga Cl\u00ednica e da Sa\u00fade, Terapeuta Familiar e Psicoterapeuta, apresentou o tema \u201cMulti-identidades\u201d; j\u00e1 Jo\u00e3o Almeida, docente no Departamento de Eletr\u00f3nica, Telecomunica\u00e7\u00f5es e Inform\u00e1tica da Universidade de Aveiro, orientou o atelier sobre \u201credes sociais\u201d.<\/p>\n\n\n\n<p>A irm\u00e3 Irene Guia, da Congrega\u00e7\u00e3o das Escravas do Sagrado Cora\u00e7\u00e3o de Jesus, orientou o atelier \u201cMulticulturalidades\u201d e o atelier sobre a Intelig\u00eancia Artificial (IA), foi da responsabilidade de Cl\u00e1udio Teixeira, Doutorado em Engenharia Inform\u00e1tica pela Universidade de Aveiro.<\/p>\n\n\n\n<p>A noite de 28 de janeiro terminou com um ser\u00e3o de conversa sobre o documento final do S\u00ednodo dos Bispo, com D. Jos\u00e9 Ornelas e D. Virg\u00edlio Antunes, bispo de Leiria-F\u00e1tima e de Coimbra, respetivamente, numa conversa moderada por Leopoldina Sim\u00f5es.<\/p>\n\n\n\n<p>No segundo dia das jornadas, 29 de janeiro, Maria Jos\u00e9 Schultz convidou o clero para uma viagem pelos relatos evang\u00e9licos que d\u00e3o conta como Jesus saiu ao encontro de pessoas, em diversas situa\u00e7\u00f5es vitais. \u201cMudou vidas, levando outros a quererem ser pessoas melhores, mais eles mesmos, na responsabilidade e no compromisso com o bem que receberam\u201d, disse. A compaix\u00e3o foi uma das atitudes destacadas pela oradora, e que em Jesus \u201cprevalecia e emergia na sua maneira de olhar, julgar e tocar os outros\u201d, um caminho da comunica\u00e7\u00e3o da f\u00e9. Foram ainda partilhadas \u201cdicas\u201d para o caminho da evangeliza\u00e7\u00e3o, como os \u201ctestemunhos cred\u00edveis e coerentes\u201d, \u201cespa\u00e7os f\u00edsicos que facilitem a partilha e o acolhimento\u201d, \u201critualidades e pr\u00e1ticas lit\u00fargicas que promovam o encontro com Jesus\u201d e \u201cespa\u00e7os onde se ensine a rezar, esperar e confiar\u201d. \u201cA mem\u00f3ria dos disc\u00edpulos de Jesus n\u00e3o inclui discursos dogm\u00e1ticos, verdades indiscut\u00edveis, regulamentos e instru\u00e7\u00f5es; n\u00e3o imp\u00f5e um modelo de pessoa nem exige um compromisso com a primeira abordagem; Como vimos, \u00e9 um processo gradual, primeiro de busca, de abordagem incipiente, de participa\u00e7\u00e3o e, finalmente, de identifica\u00e7\u00e3o\u201d, sintetizou.<\/p>\n\n\n\n<p>No \u00faltimo dia das jornadas, 30 de janeiro, a manh\u00e3 foi preenchida com duas interven\u00e7\u00f5es do padre Juan Carvajal Blanco, da Diocese de Madrid (Espanha) que falou sobre \u201cA inicia\u00e7\u00e3o dos disc\u00edpulos de Jesus, Crist\u00e3os num mundo plural\u201d. \u201cA inicia\u00e7\u00e3o crist\u00e3 \u00e9 o caminho para as pessoas aprenderem a viver crist\u00e3mente e se transformarem \u00e0 semelhan\u00e7a de Jesus\u201d. \u201cSe a f\u00e9 se prop\u00f5e como tarefa seremos considerados como gente estranha\u201d, alertou o sacerdote que abordou a catequese que n\u00e3o se pode limitar a \u201cseguir temas\u201d mas que sup\u00f5e \u201cuma transforma\u00e7\u00e3o\u201d.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"390\" height=\"260\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/24.jpg\" alt=\"\" class=\"wp-image-2727\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/24.jpg 390w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/24-300x200.jpg 300w\" sizes=\"(max-width: 390px) 100vw, 390px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"439\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/18-1024x439.jpg\" alt=\"\" class=\"wp-image-2728\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/18-1024x439.jpg 1024w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/18-300x129.jpg 300w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/18-768x329.jpg 768w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2025\/02\/18.jpg 1344w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<div style=\"height:57px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apresenta\u00e7\u00e3o do Senhor\u00a0\u2013 Ano CMensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto Neste Domingo celebramos a Festa da Apresenta\u00e7\u00e3o do Senhor. Conforme era costume na Tradi\u00e7\u00e3o Judaica todo o filho primog\u00e9nito var\u00e3o era consagrado ao Senhor. Assim, sucedeu tamb\u00e9m &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2025\/02\/02\/novos-ventos-02-de-fevereiro\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[32,8],"tags":[34,33],"class_list":["post-2724","post","type-post","status-publish","format-standard","hentry","category-novos-ventos","category-oracao","tag-boletim","tag-novos-ventos"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2724","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=2724"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2724\/revisions"}],"predecessor-version":[{"id":2729,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2724\/revisions\/2729"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=2724"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=2724"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=2724"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}