{"id":2368,"date":"2024-05-12T09:33:22","date_gmt":"2024-05-12T09:33:22","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=2368"},"modified":"2024-05-12T09:33:28","modified_gmt":"2024-05-12T09:33:28","slug":"novos-ventos-12-de-maio","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2024\/05\/12\/novos-ventos-12-de-maio\/","title":{"rendered":"Novos Ventos &#8211; 12 de Maio"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"vii-domingo-do-tempo-comum-ano-c\">Ascens\u00e3o do Senhor\u00a0\u2013\u00a0Ano B<br>Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto<\/h2>\n\n\n\n<p><a>Neste domingo celebramos o dia da Ascens\u00e3o do Senhor, isto \u00e9, Jesus \u00e9 elevado \u00e0 gl\u00f3ria do C\u00e9u. O Evangelho deste domingo relata que Jesus antes de subir ao C\u00e9u, confiou aos disc\u00edpulos uma miss\u00e3o anunciar a todos os povos o Evangelho do Reino e confere-lhes algumas capacidades de realizar milagres na vida das pessoas, mas isso requer uma ades\u00e3o e transforma\u00e7\u00e3o \u201cQuem acreditar e for baptizado ser\u00e1 salvo\u201d. Aderir \u00e0 Pessoa de Jesus Cristo, deixar-se transformar por Ele e comprometer-se na vida da Igreja. Ser baptizado \u00e9 tamb\u00e9m comprometer-se nesta grande fam\u00edlia dos crist\u00e3os, ao receber o baptismo assumo fazer parte desta grande fam\u00edlia que se re\u00fane e congrega para celebrar o dom da f\u00e9. Os milagres tamb\u00e9m acontecem num ambiente de f\u00e9. O pr\u00f3prio Jesus depara-se que na Sua terra n\u00e3o fazia muitos milagres pela falta de F\u00e9 daquela gente.<\/a><\/p>\n\n\n\n<p>Duas ideias importantes a reter hoje quando vamos pedir o baptismo para os nossos filhos \u00e9 porque nos queremos comprometer com a F\u00e9 da Igreja e devemos por isso participar ativamente na vida da comunidade crist\u00e3. Ou seja, assumir a miss\u00e3o que Jesus confiou aos disc\u00edpulos, somente nessa atitude poderei ver os milagres acontecer \u00e0 minha volta.<\/p>\n\n\n\n<p>Depois de ter dito todas estas coisas aos disc\u00edpulos, Jesus foi elevado \u00e0 gl\u00f3ria do C\u00e9u e sentou-Se \u00e0 direita de Deus. Os disc\u00edpulos deram continuidade ao mandato de Jesus. E eu estou consciente do meu compromisso na vida da comunidade crist\u00e3?<\/p>\n\n\n\n<p><strong>A leitura dos Actos dos Ap\u00f3stolos,<\/strong> repete a mensagem essencial desta festa: Jesus, depois de ter comunicado aos homens o projeto do Pai, entrou na Vida definitiva da comunh\u00e3o com Deus, a mesma vida que espera todos os que percorrem o \u201ccaminho\u201d que Jesus percorreu. Os disc\u00edpulos, testemunhas da partida de Jesus, n\u00e3o podem ficar a olhar para o c\u00e9u; mas t\u00eam de ir para o meio dos homens, seus irm\u00e3os, continuar o projeto de Jesus.<\/p>\n\n\n\n<p><strong>A leitura da Ep\u00edstola de S\u00e3o Paulo aos Ef\u00e9sios,<\/strong>&nbsp;convida os disc\u00edpulos a terem consci\u00eancia da \u201cesperan\u00e7a\u201d a que foram chamados: a Vida plena de comunh\u00e3o com Deus. \u00c9 essa \u201cesperan\u00e7a\u201d que ilumina o horizonte daqueles que fazem parte da Igreja, o \u201ccorpo\u201d do qual Cristo \u00e9 a \u201ccabe\u00e7a\u201d.<\/p>\n\n\n\n<p><strong>O Evangelho de S\u00e3o Marcos, <\/strong>Jesus ressuscitado despede-se dos disc\u00edpulos e passa-lhes o testemunho. \u00a0Os disc\u00edpulos, formados na \u201cescola\u201d de Jesus, t\u00eam como miss\u00e3o levar o Evangelho a toda a criatura e dar Vida a todos os que vivem prisioneiros do sofrimento e da morte. De junto do Pai, Jesus continuar\u00e1 a acompanh\u00e1-los e a mostrar-lhes os caminhos que eles devem percorrer.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><u>Conclus\u00e3o do Santo Evangelho Segundo S\u00e3o Marcos<\/u><\/strong><\/h2>\n\n\n\n<p>Naquele tempo, Jesus apareceu aos Onze e disse-lhes: \u00abIde por todo o mundo e pregai o Evangelho a toda a criatura. Quem acreditar e for batizado ser\u00e1 salvo; mas quem n\u00e3o acreditar ser\u00e1 condenado. Eis os milagres que acompanhar\u00e3o os que acreditarem: expulsar\u00e3o os dem\u00f3nios em meu nome; falar\u00e3o novas l\u00ednguas; se pegarem em serpentes ou beberem veneno, n\u00e3o sofrer\u00e3o nenhum mal; e quando impuserem as m\u00e3os sobre os doentes, eles ficar\u00e3o curados\u00bb. E assim o Senhor Jesus, depois de ter falado com eles, foi elevado ao C\u00e9u e sentou-Se \u00e0 direita de Deus. Eles partiram a pregar por toda a parte, e o Senhor cooperava com eles, confirmando a sua palavra com os milagres que a acompanhavam. <strong>Palavra da Salva\u00e7\u00e3o<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/100.png\" alt=\"\" class=\"wp-image-2369\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/100.png 640w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/100-300x169.png 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p><strong><u>Palavra de Vida (Maio)<\/u><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00abQuem n\u00e3o ama n\u00e3o conheceu Deus, porque Deus \u00e9 amor\u00bb.<\/strong>&nbsp;(<em>1Jo&nbsp;<\/em>4,8)<\/h2>\n\n\n\n<p>Para recordar a ess\u00eancia da revela\u00e7\u00e3o recebida, o autor sublinha que, em Jesus, Deus tomou a iniciativa de nos amar, assumindo totalmente a exist\u00eancia humana, com todos os seus limites e as suas fraquezas.\u00a0 Na cruz, Jesus partilhou e experimentou pessoalmente a nossa separa\u00e7\u00e3o do Pai. Dando-se completamente, resgatou-a com um amor sem limites nem condi\u00e7\u00f5es. Demonstrou-nos a medida do amor, que j\u00e1 nos tinha ensinado com palavras e com a vida.\u00a0 Pelo exemplo de Jesus, compreendemos que amar verdadeiramente implica coragem, esfor\u00e7o e o risco de termos que enfrentar contrariedades e sofrimentos. Mas quem ama assim participa da vida de Deus e experimenta a Sua liberdade e a alegria de quem se d\u00e1.\u00a0 Amando como Jesus nos amou, libertamo-nos do ego\u00edsmo que impede a comunh\u00e3o com os irm\u00e3os e com Deus. Podemos, assim, experiment\u00e1-la.<em>\u00a0Silvano Malini<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"810\" height=\"262\" data-id=\"2371\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/101.png\" alt=\"\" class=\"wp-image-2371\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/101.png 810w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/101-300x97.png 300w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/101-768x248.png 768w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"765\" data-id=\"2370\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/102-1024x765.jpg\" alt=\"\" class=\"wp-image-2370\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/102-1024x765.jpg 1024w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/102-300x224.jpg 300w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/102-768x574.jpg 768w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/102-1536x1148.jpg 1536w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/102.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><u>TESTEMUNHO DE VIDA<\/u><\/strong><\/h2>\n\n\n\n<p>Na nossa cidade todos os domingos, algumas par\u00f3quias preparam refei\u00e7\u00f5es para os sem-abrigo. Um dia oferecemo-nos para ajudar. Prepar\u00e1mos a sala e acolhemos as pessoas. Vieram vinte. Servimos \u00e0 mesa e ouvimos as suas hist\u00f3rias: quanta dor e sofrimento havia por detr\u00e1s de cada uma! Perguntaram nos quem \u00e9ramos e qual era o nosso ideal, n\u00f3s fal\u00e1mos-lhes de n\u00f3s e do nosso ideal: &#8220;o mundo unido&#8221;. Alguns agradeceram-nos dizendo estarem contentes pela nossa companhia, um deles quis ficar a ajudar nos. Ver a alegria de pessoas tantas vezes s\u00f3s e em sofrimento, deu-nos uma felicidade ainda maior! <em>Um grupo de rapazes- It\u00e1lia<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><u>S\u00ednodo. Portugal: relat\u00f3rio alerta para o clericalismo e destaca papel da mulher na Igreja<\/u><\/strong><\/h2>\n\n\n\n<p><strong>Clericalismo e resist\u00eancia a mudan\u00e7as<\/strong><\/p>\n\n\n\n<p>Ressalta do texto da CEP a preocupa\u00e7\u00e3o de \u201ccontinuar a fazer um discernimento sobre algumas quest\u00f5es doutrinais\/pastorais que ainda causam d\u00favida, controv\u00e9rsia ou desacordo na vida da Igreja\u201d. S\u00e3o elas \u201ca moral sexual, o celibato dos padres, o envolvimento de ex-padres casados, a possibilidade de ordena\u00e7\u00e3o de mulheres\u201d. A CEP assinala a exist\u00eancia de \u201cresist\u00eancia a mudan\u00e7as\u201d apontando a necessidade de se \u201ccontinuar a refletir sobre os fatores que motivam a indiferen\u00e7a de muitos, as resist\u00eancias \u00e0s mudan\u00e7as e os caminhos para as ir ultrapassando\u201d. Especial destaque para o reconhecimento de que a \u201ca Igreja continua muito centrada no clero e em alguns leigos \u2018clericalizados\u2019. \u201cO clericalismo, que, entre outros aspetos, se manifesta numa conce\u00e7\u00e3o de privil\u00e9gio pessoal, num estilo de poder mundano e na recusa a prestar contas, \u00e9 um obst\u00e1culo s\u00e9rio ao exerc\u00edcio de um minist\u00e9rio ordenado aut\u00eantico\u201d, refere o relat\u00f3rio. \u201cO clericalismo atinge tamb\u00e9m os leigos com responsabilidades na vida da Igreja local e das comunidades. Combater a clericaliza\u00e7\u00e3o do laicado passa muito pela rotatividade nas lideran\u00e7as e pelo desenvolvimento de metodologias de participa\u00e7\u00e3o comunit\u00e1ria\u201d, afirma o documento.<\/p>\n\n\n\n<p><strong>O papel da mulher na vida eclesial<\/strong><\/p>\n\n\n\n<p>No relat\u00f3rio da CEP \u00e9 \u201creconhecida a import\u00e2ncia de valorizar o papel das mulheres na vida eclesial e assegurar que possam participar nos processos de decis\u00e3o\u201d. Para essa participa\u00e7\u00e3o ser concreta as mulheres devem assumir \u201cpap\u00e9is de lideran\u00e7a, especificamente nos conselhos pastorais e econ\u00f3micos\u201d. \u201cDeve-se procurar a meta da paridade, reconhecendo explicitamente o contributo crucial das mulheres, n\u00e3o apenas na pastoral e nos minist\u00e9rios, mas tamb\u00e9m na miss\u00e3o da Igreja junto das comunidades. Existe uma clara perce\u00e7\u00e3o de que a Igreja tem muito a ganhar com uma interven\u00e7\u00e3o mais relevante das mulheres, de um modo particular, no an\u00fancio e na medita\u00e7\u00e3o da Palavra de Deus, para uma verdadeira viv\u00eancia sinodal e reconhecimento pleno dos seus dons e capacidades\u201d, sustenta o documento. Corresponsabilidade, minist\u00e9rios e juventude Neste documento \u00e9 sublinhado que a \u201ccorresponsabilidade diferenciada na miss\u00e3o de todos os membros do Povo de Deus, de acordo com as voca\u00e7\u00f5es, carismas, servi\u00e7os, e minist\u00e9rios, deve ser o modelo normal da vida eclesial\u201d.<\/p>\n\n\n\n<p>Esta forma de trabalho permite organizar a \u201cIgreja como uma fam\u00edlia e n\u00e3o como uma estrutura, criando meios para a valoriza\u00e7\u00e3o da rela\u00e7\u00e3o fraternal e teologal nas comunidades, assim como a aten\u00e7\u00e3o particular a alguns setores: o mundo da sa\u00fade, do servi\u00e7o aos mais pobres e o acolhimento aos de fora\u201d. \u201cEm ordem a implementar um modelo pastoral correspons\u00e1vel \u00e9 feita a sugest\u00e3o de se criar a figura de um \u2018coordenador pastoral\u2019 como elo entre o p\u00e1roco e a comunidade. \u00c9 sugerida, uma maior celeridade e participa\u00e7\u00e3o laical nos processos de nomea\u00e7\u00e3o dos bispos.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"422\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/103.jpg\" alt=\"\" class=\"wp-image-2372\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/103.jpg 750w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/103-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><u>Pr\u00f3ximas Atividades Paroquiais<\/u><\/strong><\/h2>\n\n\n\n<p>\u25ca Dia 18 de Maio Noite de Fados no Sal\u00e3o da Junta de Freguesia do Bunheiro angaria\u00e7\u00e3o de fundos para a constru\u00e7\u00e3o do sal\u00e3o paroquial;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/95-1-724x1024.jpg\" alt=\"\" class=\"wp-image-2373\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/95-1-724x1024.jpg 724w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/95-1-212x300.jpg 212w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/95-1-768x1087.jpg 768w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/95-1-1086x1536.jpg 1086w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/95-1-1447x2048.jpg 1447w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/95-1-scaled.jpg 1809w\" sizes=\"(max-width: 724px) 100vw, 724px\" \/><\/figure>\n<\/div>\n\n\n<p>\u25ca Dia 26 de Maio, haver\u00e1 a Primeira Comunh\u00e3o<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"784\" height=\"1024\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/104-784x1024.jpg\" alt=\"\" class=\"wp-image-2374\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/104-784x1024.jpg 784w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/104-230x300.jpg 230w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/104-768x1003.jpg 768w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/104.jpg 980w\" sizes=\"(max-width: 784px) 100vw, 784px\" \/><\/figure>\n<\/div>\n\n\n<p>\u25ca Dia 30 de Maio, Prociss\u00e3o na Ria do Corpo de Deus.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/96-1.jpg\" alt=\"\" class=\"wp-image-2375\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/96-1.jpg 720w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/05\/96-1-225x300.jpg 225w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<div style=\"height:43px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ascens\u00e3o do Senhor\u00a0\u2013\u00a0Ano BMensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto Neste domingo celebramos o dia da Ascens\u00e3o do Senhor, isto \u00e9, Jesus \u00e9 elevado \u00e0 gl\u00f3ria do C\u00e9u. O Evangelho deste domingo relata que Jesus antes de subir &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2024\/05\/12\/novos-ventos-12-de-maio\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[32,8],"tags":[34,33],"class_list":["post-2368","post","type-post","status-publish","format-standard","hentry","category-novos-ventos","category-oracao","tag-boletim","tag-novos-ventos"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=2368"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2368\/revisions"}],"predecessor-version":[{"id":2376,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2368\/revisions\/2376"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=2368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=2368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=2368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}