{"id":2353,"date":"2024-05-05T09:04:14","date_gmt":"2024-05-05T09:04:14","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=2353"},"modified":"2024-05-05T09:04:48","modified_gmt":"2024-05-05T09:04:48","slug":"05-a-12-de-maio","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2024\/05\/05\/05-a-12-de-maio\/","title":{"rendered":"05 a 12 de Maio"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Informa\u00e7\u00f5es<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Na Segunda-feira, dia (06\/05) haver\u00e1:\n<ul class=\"wp-block-list\">\n<li>Eucaristia na Igreja Matriz, \u00e0s 19:00;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Na Quarta-feira, dia (08\/05) haver\u00e1:<ul><li>Atendimento Paroquial das 16:00 \u00e0s 19:00;<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Eucaristia nas Quintas do Norte, \u00e0s 20:00;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Na Sexta-feira, dia (10\/05) haver\u00e1:<ul><li>Atendimento Paroquial das 16:00 \u00e0s 18:00;<\/li><\/ul><ul><li>Adora\u00e7\u00e3o ao Sant\u00edssimo Sacramento \u201cCatequeses Congresso Eucar\u00edstico\u201d, \u00e0s 18:15;<\/li><\/ul><ul><li>Eucaristia na Igreja Matriz, \u00e0s 19:00;<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Reuni\u00e3o de Prepara\u00e7\u00e3o de Baptismos a realizar no m\u00eas de Maio e Junho e das crian\u00e7as da 1\u00aa Comunh\u00e3o, \u00e0s 21:15;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No S\u00e1bado, dia (11\/05) haver\u00e1:<ul><li>Ter\u00e7o orientado pela Catequese, \u00e0s 16:00;<\/li><\/ul><ul><li>Eucaristia na Igreja Paroquial, \u00e0s 17:00;&nbsp;<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Reuni\u00e3o do Conselho Econ\u00f3mico, \u00e0s 18:30;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No Domingo, dia (12\/05) haver\u00e1:<ul><li>Eucaristia na Capela das Quintas do Norte, \u00e0s 8:00;<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Eucaristia na Igreja Matriz, \u00e0s 11:00;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>A venda dos bolos no fim-de-semana passado esteve ao cuidado do Grupo de Catequese 3\u00baAno B, no s\u00e1bado o valor foi de 71\u20ac e no domingo o valor foi de 72\u20ac e nas Quintas do Norte esteve ao cuidado do grupo dos Ministros da Comunh\u00e3o e o valor foi de 84\u20ac.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No dia 18 de Maio haver\u00e1 no sal\u00e3o da Junta do Bunheiro, \u00e0s 21:30 uma noite de fados com o objetivo de angaria\u00e7\u00e3o de fundos para a constru\u00e7\u00e3o do nosso sal\u00e3o paroquial os bilhetes poder\u00e3o ser adquiridos no final das eucaristias.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No dia 30 de Maio ser\u00e1 o Corpo de Deus, como habitual haver\u00e1 a prociss\u00e3o na ria pedimos a todas as pessoas que tenham embarca\u00e7\u00f5es para se juntar a n\u00f3s afim de dignificar uma das nossas prociss\u00f5es que t\u00eam a sua beleza e podermos desta forma louvar e adorar o Sant\u00edssimo Sacramento.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>O grupo das zeladoras das toalhas de altar agradece a todas as pessoas que deram o seu donativo para aquisi\u00e7\u00e3o de novas toalhas. O valor adquirido deu para comprar os dois conjuntos das toalhas as zeladoras agradecem a generosidade de todos. Obrigado<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Durante o m\u00eas de Maio far-se-\u00e1 a recita\u00e7\u00e3o do Ter\u00e7o, com os seguintes hor\u00e1rios:<ul><li>Segunda a Sexta-feira na Igreja da Torreira, \u00e0s 18:30;<\/li><\/ul><ul><li>S\u00e1bados e Domingos na Igreja da Torreira, \u00e0s 16:00;<\/li><\/ul>\n<ul class=\"wp-block-list\">\n<li>Segunda a Sexta-feira nas Quintas do Norte, \u00e0s 20:30;<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No pr\u00f3ximo s\u00e1bado, dia 11 de Maio haver\u00e1 o Encerramento do Ano Jubilar em Aveiro, acolhimento, \u00e0s 14.00 na Pra\u00e7a da Rep\u00fablica e a Eucaristia, \u00e0s 17:30 na Pra\u00e7a do Marqu\u00eas de Pombal.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:44px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"intencoes-de-missa\">Inten\u00e7\u00f5es de Missa<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"segunda-feira-21-igreja-matriz-19-00h\"><strong>Segunda-feira, 06 \u2013\u00a0Igreja Matriz, 19:00h<\/strong><\/h3>\n\n\n\n<p><strong>+ Maria Teresa Alves Esteves Pereira, pais e irm\u00e3o.<\/strong><br><strong>+ Ant\u00f3nio Jos\u00e9 Azevedo Henriques.<\/strong><br><strong>+ Aurora da Silva Pereira e irm\u00e3os.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"quarta-feira-23-quintas-do-norte-20-00h\"><strong>Quarta-feira, 08 \u2013\u00a0Quintas do Norte, 20:00h<\/strong><\/h3>\n\n\n\n<p><strong>+ Celso Valente dos Santos.<\/strong><br><strong>+ Fernando Dias da Silva Tavares.<\/strong><br><strong>+ Beatriz Dias de Oliveira.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"sexta-feira-25-igreja-matriz-19-00h\"><strong>Sexta-feira, 10 \u2013\u00a0\u00a0Igreja Matriz, 19:00h<\/strong><\/h3>\n\n\n\n<p><strong>+ Maria Jos\u00e9 da Cunha, Filipe Carlos e Jo\u00e3o Eus\u00e9bio Vieira.<\/strong><br><strong>+ Anivers\u00e1rio de falecimento de Ros\u00e1lia Seabra, Carolina Cunha e Alfredo Evaristo.<\/strong><br><strong>+ Rosa Gavina Marques, Manuel Tavares da Silva, \u00c2ngela Gavina Marques, Tobias Gavina Marques e Ant\u00f3nio Jorge da Silva Marques.<\/strong><br><strong>+ Albertina Rosa Castelhana Vieira.<\/strong><br><strong>+ Tiago Valente Esperan\u00e7a, esposa e filhos.<\/strong><br><strong>+ Pelas Almas do Purgat\u00f3rio.<\/strong><\/p>\n\n\n\n<div style=\"height:51px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informa\u00e7\u00f5es Inten\u00e7\u00f5es de Missa Segunda-feira, 06 \u2013\u00a0Igreja Matriz, 19:00h + Maria Teresa Alves Esteves Pereira, pais e irm\u00e3o.+ Ant\u00f3nio Jos\u00e9 Azevedo Henriques.+ Aurora da Silva Pereira e irm\u00e3os. Quarta-feira, 08 \u2013\u00a0Quintas do Norte, 20:00h + Celso Valente dos Santos.+ Fernando &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2024\/05\/05\/05-a-12-de-maio\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[9,31],"tags":[30],"class_list":["post-2353","post","type-post","status-publish","format-standard","hentry","category-informacao","category-intencoes","tag-informacao-semanal"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=2353"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2353\/revisions"}],"predecessor-version":[{"id":2354,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2353\/revisions\/2354"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=2353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=2353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=2353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}