{"id":2335,"date":"2024-04-21T09:19:32","date_gmt":"2024-04-21T09:19:32","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=2335"},"modified":"2024-04-21T09:20:03","modified_gmt":"2024-04-21T09:20:03","slug":"novos-ventos-21-de-abril","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2024\/04\/21\/novos-ventos-21-de-abril\/","title":{"rendered":"Novos Ventos &#8211; 21 de Abril"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"vii-domingo-do-tempo-comum-ano-c\">IV Domingo da P\u00e1scoa \u2013\u00a0Ano B<br>Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto<\/h2>\n\n\n\n<p>Hoje celebramos o domingo do Bom Pastor. Jesus \u00e9 o Verdadeiro Pastor que cuida e trata das ovelhas que andam tresmalhadas e perdidas no meio de uma vida multifacetada, mas vazias de sentido. O evangelista faz um paralelismo entre o Pastor e o mercen\u00e1rio, enquanto o Pastor cuida e protege o rebanho o mercen\u00e1rio vem para roubar e dispersar. Quantas vezes, deixemos que a nossa vida ande sem rumo e n\u00e3o deixemos que este Bom Pastor nos guie por caminhos seguros. A maior prova de Amor de Jesus pelo seu povo \u00e9 at\u00e9 ao ponto de doar a Sua vida por cada um de n\u00f3s. Quantas vezes, na Sagrada Escritura vemos atitude de Jesus que se compadece das multid\u00f5es que andam \u00e0 deriva como ovelhas sem pastor.<\/p>\n\n\n\n<p>As sociedades de hoje refletem muito esta falta de compromisso com Deus e a Igreja, precisamos da Igreja apenas para realizar os Sacramentos como algu\u00e9m que negoceia para obter um papel mas o seu cora\u00e7\u00e3o est\u00e1 distante de Deus. Jesus compadece-se destas multid\u00f5es que andam afastadas da Igreja, que ainda n\u00e3o fizeram a experi\u00eancia de descobrir o Amor de Jesus por cada um deles. Andam famintos mas n\u00e3o buscam o verdadeiro alimento que sacia. Outros, apenas vivem o relativismo e prescindem de Deus. As multid\u00f5es de outrora s\u00e3o como as multid\u00f5es de hoje que s\u00f3 buscam milagres, mas n\u00e3o se deixam impressionar pelo relacionamento pessoal com Cristo.<\/p>\n\n\n\n<p>Pe\u00e7amos ao Senhor que nos abra o cora\u00e7\u00e3o, para podermos descobrir o Seu Amor e procuremos rezar pelos pastores que o Senhor colocou para servir as nossas comunidades paroquiais.<\/p>\n\n\n\n<p><strong>A leitura dos Actos dos Ap\u00f3stolos,<\/strong> traz-nos um testemunho de Pedro, proclamado em Jerusal\u00e9m diante das autoridades judaicas: Jesus \u00e9 o \u00fanico Salvador, j\u00e1 que \u201cn\u00e3o existe debaixo do c\u00e9u outro nome, dado aos homens, pelo qual possamos ser salvos\u201d. \u00c9 a forma, muito particular, que Pedro encontrou para dizer que Jesus \u00e9 o \u00fanico pastor que nos conduz em dire\u00e7\u00e3o \u00e0 Vida verdadeira.<\/p>\n\n\n\n<p><strong>A leitura da Ep\u00edstola de S\u00e3o Jo\u00e3o,<\/strong>&nbsp;o autor da primeira Carta de Jo\u00e3o convida-nos a contemplar o amor de Deus pelo homem. \u00c9 porque nos ama com um \u201camor admir\u00e1vel\u201d que Deus est\u00e1 apostado em levar-nos a superar a nossa condi\u00e7\u00e3o de debilidade e de fragilidade. Por isso, Deus enviou-nos Jesus, o Bom Pastor.<\/p>\n\n\n\n<p><strong>O Evangelho de S\u00e3o Jo\u00e3o, <\/strong>\u00e9 o pr\u00f3prio Jesus que se apresenta como \u201co Bom Pastor\u201d. Ele ama as suas ovelhas, cuida delas em cada passo do caminho, d\u00e1 a vida por elas, se for necess\u00e1rio. As ovelhas de Jesus sabem que podem confiar n\u2019Ele, incondicionalmente. Com esta bela imagem, somos convidados a seguir Jesus e a fazer d\u2019Ele a refer\u00eancia fundamental \u00e0 volta da qual constru\u00edmos a nossa vida.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><u>Evangelho de Nosso Senhor Jesus Cristo Segundo S\u00e3o Jo\u00e3o<\/u><\/strong><\/h2>\n\n\n\n<p>Naquele tempo, disse Jesus: \u00abEu sou o Bom Pastor. O bom pastor d\u00e1 a vida pelas suas ovelhas. O mercen\u00e1rio, como n\u00e3o \u00e9 pastor, nem s\u00e3o suas as ovelhas, logo que v\u00ea vir o lobo, deixa as ovelhas e foge, enquanto o lobo as arrebata e dispersa. O mercen\u00e1rio n\u00e3o se preocupa com as ovelhas. Eu sou o Bom Pastor: conhe\u00e7o as minhas ovelhas, e as minhas ovelhas conhecem-Me, do mesmo modo que o Pai Me conhece e Eu conhe\u00e7o o Pai; Eu dou a vida pelas minhas ovelhas. Tenho ainda outras ovelhas que n\u00e3o s\u00e3o deste redil e preciso de as reunir; elas ouvir\u00e3o a minha voz e haver\u00e1 um s\u00f3 rebanho e um s\u00f3 Pastor. Por isso o Pai Me ama: porque dou a minha vida, para poder retom\u00e1-la. Ningu\u00e9m Ma tira, sou Eu que a dou espontaneamente. Tenho o poder de a dar e de a retomar: foi este o mandamento que recebi de meu Pai\u00bb. <strong>Palavra da Salva\u00e7\u00e3o<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"212\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/81-1024x212.jpg\" alt=\"\" class=\"wp-image-2336\" style=\"width:704px;height:auto\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/81-1024x212.jpg 1024w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/81-300x62.jpg 300w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/81-768x159.jpg 768w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/81.jpg 1124w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p><strong><u>Palavra de Vida (Abril)<\/u><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>\u00abCom grande poder, os ap\u00f3stolos davam testemunho da ressurrei\u00e7\u00e3o do Senhor Jesus, e gozavam todos de uma grande simpatia\u00bb.&nbsp;<\/strong>(<em>At&nbsp;<\/em>4,33)<\/h2>\n\n\n\n<p>O modo mais eficaz de dar testemunho do Ressuscitado \u00e9 mostrar que Ele est\u00e1 vivo e habita no meio de n\u00f3s. \u00abSe vivermos a sua Palavra, [\u2026] mantendo aceso no cora\u00e7\u00e3o o amor ao pr\u00f3ximo, se nos esfor\u00e7armos, de modo especial, por conservar sempre o amor rec\u00edproco entre n\u00f3s, ent\u00e3o o Ressuscitado viver\u00e1 em n\u00f3s, viver\u00e1 no meio de n\u00f3s e irradiar\u00e1 \u00e0 nossa volta a sua luz e a sua gra\u00e7a, transformando os ambientes com frutos incalcul\u00e1veis. Ser\u00e1 Ele, mediante o seu Esp\u00edrito, a guiar os nossos passos e as nossas atividades. Ser\u00e1 Ele a determinar as circunst\u00e2ncias e a proporcionar-nos as ocasi\u00f5es para levar a Sua vida \u00e0s pessoas que d\u2019Ele necessitam\u00bb<sup>[2]<\/sup>.<em>Patrizia Mazzola\u00a0<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"243\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/82-1024x243.jpg\" alt=\"\" class=\"wp-image-2337\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/82-1024x243.jpg 1024w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/82-300x71.jpg 300w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/82-768x182.jpg 768w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/82.jpg 1127w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><u>Testemunho<\/u><\/strong><\/h2>\n\n\n\n<p>Na Mari\u00e1polis, na Col\u00f4mbia, estavam presentes muitas pessoas, adultos e crian\u00e7as que procuravam viver a lei do amor. Um senhor que foi pela primeira vez n\u00e3o quis entrar na sala com os adultos e ficou passeando no jardim. Ali estavam muitos gen4 jogando. A um certo momento, uma delas ficou com raiva e se afastou. As outras crian\u00e7as pararam e se entreolharam. Depois, um gen4, correndo, a alcan\u00e7ou e lhe disse: \u201cVoc\u00ea me perdoa?\u201d<\/p>\n\n\n\n<p>A gen4 olhou para ele, sorriu e voltaram a brincar junto com os demais. O senhor, que estava observando a cena atr\u00e1s de algumas plantas, ficou tocado! Tinha \u201cvisto realmente\u201d o amor rec\u00edproco! Os gen4 tinham dado testemunho!<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"362\" height=\"241\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/83.jpg\" alt=\"\" class=\"wp-image-2338\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/83.jpg 362w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/83-300x200.jpg 300w\" sizes=\"(max-width: 362px) 100vw, 362px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">\u201cIntelig\u00eancia Artificial\u201d: tema de reflex\u00e3o na 61\u00aa Assembleia Geral dos Bispos do Brasil<\/h2>\n\n\n\n<p><strong>Os trabalhos<\/strong><\/p>\n\n\n\n<p>Em seguida, \u00e0s 10h, os jornalistas voltaram a se encontrar com os bispos na&nbsp;Coletiva de Imprensa. Os bispos indicados para participar da coletiva nesta segunda foram: o bispo de Imperatriz\u2013MA,&nbsp;dom Vilson Basso, que falou sobre o tema&nbsp;\u201cDesafios e Luzes para a evangeliza\u00e7\u00e3o das juventudes\u201d; o bispo de Rondon\u00f3polis-Guiratinga\u2013MT,&nbsp;dom Maur\u00edcio da Silva Jardim, que apresentou os&nbsp;projetos mission\u00e1rios&nbsp;e Igrejas Irm\u00e3s, e tamb\u00e9m o bispo de Campo Limpo (SP),&nbsp;dom Valdir Jos\u00e9 de Castro, que conversou sobre o tema da&nbsp;Intelig\u00eancia Artificial. Ap\u00f3s a Coletiva, o episcopado retornou para a&nbsp;12\u00aa sess\u00e3o, que centralizou a sua aten\u00e7\u00e3o sobre o tema central da Assembleia:&nbsp;\u201ca atualiza\u00e7\u00e3o das diretrizes gerais da a\u00e7\u00e3o evangelizadora da Igreja no Brasil\u201d. Os bispos continuaram o caminho de discernimento sobre as diretrizes na din\u00e2mica das&nbsp;45 mesas sinodais.<\/p>\n\n\n\n<p><strong>Desafios e Luzes para a evangeliza\u00e7\u00e3o das juventudes<\/strong><\/p>\n\n\n\n<p>O tema da Intelig\u00eancia Artificial foi abordado por Dom Valdir Jos\u00e9,&nbsp;que explicou que o episcopado est\u00e1 refletindo esse tema, que n\u00e3o \u00e9 propriamente novidade, mas tem se desenvolvido cada vez mais.<\/p>\n\n\n\n<p>\u201cDevemos tudo isso ao Papa Francisco, que tem incentivado a Igreja a entrar, refletir, pensar e agir pastoralmente, levando em considera\u00e7\u00e3o a intelig\u00eancia artificial.&nbsp;Se os senhores se lembram, o tema para o&nbsp;Dia Mundial da Paz foi &#8216;Intelig\u00eancia artificial e paz&#8217;,&nbsp;e o tema para o pr\u00f3ximo&nbsp;Dia Mundial das Comunica\u00e7\u00f5es \u00e9 &#8216;Intelig\u00eancia artificial e sabedoria do cora\u00e7\u00e3o, para uma comunica\u00e7\u00e3o plenamente humana&#8217;\u201d. O bispo explicou que \u00e9 necess\u00e1rio que a Igreja, como perita em humanidade, pense como ela pode orientar eticamente o uso das intelig\u00eancias artificiais.&nbsp;Como utilizar as intelig\u00eancias artificiais para o servi\u00e7o da Igreja de evangeliza\u00e7\u00e3o? \u201cVamos partir do&nbsp;positivo das intelig\u00eancias artificiais.&nbsp;Como a Igreja pode utilizar esses meios e recursos para&nbsp;anunciar o Evangelho, para comunicar-se com a cultura de hoje\u201d. E finalizou, citando uma frase de Papa Francisco sobre o assunto:&nbsp;\u201cCorre-se o risco de ser rico em t\u00e9cnica e pobre em humanidade\u201d. \u201cEnt\u00e3o n\u00f3s temos que humanizar a tecnologia. N\u00e3o negar as tecnologias,&nbsp;mas como utiliz\u00e1-las levando ao o cora\u00e7\u00e3o humano e tornando a humanidade mais humana?\u201d. Dom Vilsom Basso, bispo referencial para a Pastoral da Juventude, iniciou apresentando o sonho do&nbsp;Papa Francisco&nbsp;com o&nbsp;S\u00ednodo de 2018, que fala que a Igreja deve investir tempo, energia e recursos financeiros na evangeliza\u00e7\u00e3o dos jovens.&nbsp; \u201cA&nbsp;Christus Vivit&nbsp;&#8211; disse ele &#8211; que foi a&nbsp;exorta\u00e7\u00e3o apost\u00f3lica p\u00f3s-sinodal,&nbsp;onde papa Francisco coloca meios para uma nova pastoral com os jovens, colocando a Boa Nova de que&nbsp;Deus ama os jovens, que o Cristo derramou seu sangue por eles e que Jesus vive e est\u00e1 sempre presente ao lado dos jovens\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"523\" height=\"288\" data-id=\"2340\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/84.jpg\" alt=\"\" class=\"wp-image-2340\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/84.jpg 523w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/84-300x165.jpg 300w\" sizes=\"(max-width: 523px) 100vw, 523px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"596\" height=\"287\" data-id=\"2339\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/85.jpg\" alt=\"\" class=\"wp-image-2339\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/85.jpg 596w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/04\/85-300x144.jpg 300w\" sizes=\"(max-width: 596px) 100vw, 596px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Prossegue o encontro do C9 no Vaticano<\/h2>\n\n\n\n<p><strong>Os trabalhos de fevereiro<\/strong><\/p>\n\n\n\n<p>A \u00faltima sess\u00e3o de trabalho decorreu de 5 a 7 de fevereiro e contou com a participa\u00e7\u00e3o de tr\u00eas mulheres que ofereceram sua contribui\u00e7\u00e3o sobre o tema do papel feminino na Igreja: irm\u00e3 Linda Pocher, filha de Maria Auxiliadora e professora de Cristologia e Mariologia na Pontif\u00edcia Faculdade de Ci\u00eancias da Educa\u00e7\u00e3o Auxilium de Roma; Giuliva Di Berardino, consagrada da Ordo Virginum da Diocese de Verona, professora e respons\u00e1vel de cursos de espiritualidade e exerc\u00edcios espirituais; Jo Bailey Wells, bispa da Igreja da Inglaterra e subsecret\u00e1ria geral da Comunh\u00e3o Anglicana. No centro das reuni\u00f5es de fevereiro dos cardeais com o Papa e o secret\u00e1rio do Conselho, foram abordados tamb\u00e9m os percursos sinodais em andamento na Igreja e o tema da evangeliza\u00e7\u00e3o com os relat\u00f3rios do cardeal Luis Antonio Tagle e do arcebispo Rino Fisichella, pr\u00f3-prefeitos do Dicast\u00e9rio para a Evangeliza\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>O &#8220;novo&#8221; C9<\/strong><\/p>\n\n\n\n<p>O Conselho de Cardeais, ap\u00f3s a renova\u00e7\u00e3o do organismo pelo Papa em 7 de mar\u00e7o de 2023, \u00e9 composto pelos cardeais Pietro Parolin, secret\u00e1rio de Estado; Fernando V\u00e9rgez Alzaga, presidente da Pontif\u00edcia Comiss\u00e3o para o Estado da Cidade do Vaticano e do Governatorato do Estado da Cidade do Vaticano; Fridolin Ambongo Besungu, arcebispo de Kinshasa; Oswald Gracias, arcebispo de Mumbai; Se\u00e1n Patrick O&#8217;Malley, arcebispo de Boston; Juan Jos\u00e9 Omella Omella, arcebispo de Barcelona; G\u00e9rald Lacroix, arcebispo de Quebec; Jean-Claude Hollerich, arcebispo de Luxemburgo; S\u00e9rgio da Rocha, arcebispo de Salvador (Bahia). O secret\u00e1rio do C9 \u00e9 dom Marco Mellino. A primeira reuni\u00e3o do novo C9 realizou-se em 24 de abril do ano passado.<\/p>\n\n\n\n<div style=\"height:62px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>IV Domingo da P\u00e1scoa \u2013\u00a0Ano BMensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto Hoje celebramos o domingo do Bom Pastor. Jesus \u00e9 o Verdadeiro Pastor que cuida e trata das ovelhas que andam tresmalhadas e perdidas no meio de &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2024\/04\/21\/novos-ventos-21-de-abril\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[32,8],"tags":[34,33],"class_list":["post-2335","post","type-post","status-publish","format-standard","hentry","category-novos-ventos","category-oracao","tag-boletim","tag-novos-ventos"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=2335"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2335\/revisions"}],"predecessor-version":[{"id":2341,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2335\/revisions\/2341"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=2335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=2335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=2335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}