{"id":2259,"date":"2024-02-25T08:32:57","date_gmt":"2024-02-25T08:32:57","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=2259"},"modified":"2024-02-25T08:33:03","modified_gmt":"2024-02-25T08:33:03","slug":"novos-ventos-25-de-fevereiro","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2024\/02\/25\/novos-ventos-25-de-fevereiro\/","title":{"rendered":"Novos Ventos &#8211; 25 de Fevereiro"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"vii-domingo-do-tempo-comum-ano-c\">II Domingo da Quaresma \u2013\u00a0Ano B<br>Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto<\/h2>\n\n\n\n<p>Neste II domingo da Quaresma a liturgia apresenta o relato da Transfigura\u00e7\u00e3o do Senhor. Na verdade, mesmo antes da Paix\u00e3o e Morte Jesus faz antever aos disc\u00edpulos a experi\u00eancia do Para\u00edso, isto \u00e9, a realidade do C\u00e9u. Os disc\u00edpulos ao entrar nessa experi\u00eancia do Para\u00edso v\u00e3o dizer \u201cMestre, como \u00e9 bom estarmos aqui! Fa\u00e7amos tr\u00eas tendas: uma para Ti, outra para Mois\u00e9s e outra para Elias\u201d. A experi\u00eancia do Para\u00edso f\u00e1-los esquecer de si pr\u00f3prios \u00e9 t\u00e3o importante estar mergulhados no Amor divino que para eles nada mais interessa. Mas, na verdade o que v\u00eam os disc\u00edpulos? A gl\u00f3ria da Ressurrei\u00e7\u00e3o de Jesus, o rosto e as vestes de Jesus ficaram resplandecentes e Mois\u00e9s e Elias que conversavam com Jesus. N\u00f3s temos muita dificuldade em entender esta experi\u00eancia M\u00edstica \u00e0 qual os Ap\u00f3stolos t\u00eam a especial gra\u00e7a de participar. No entanto, alguns santos t\u00eam esse privil\u00e9gio de entrar no sobrenatural e receber gra\u00e7as especiais; como por exemplo S\u00e3o Francisco de Assis que recebeu os estigmas da Paix\u00e3o do Senhor, S\u00e3o Padre Pio de Pietrelcina, a Besta Alexandrina que embora n\u00e3o tenha recebido os estigmas sofreu no seu corpo a Paix\u00e3o do Senhor e tantos outros que tiveram revela\u00e7\u00f5es m\u00edsticas.<\/p>\n\n\n\n<p>Esta semana somos desafiados a ser pedras de Empatia, isto \u00e9, convidados a olhar para as nossas m\u00e3os e transformar os nossos gestos, por vezes, frios e descomprometidos, em aut\u00eanticas Pedras de Toque. Que as nossas a\u00e7\u00f5es estejam sempre a transbordar do amor que recebemos e aprendemos de Jesus.<\/p>\n\n\n\n<p><strong>O Livro do G\u00e9nesis,<\/strong> apresenta-se a figura de Abra\u00e3o como paradigma do crente. Abra\u00e3o \u00e9 o homem de f\u00e9 inabal\u00e1vel, que vive numa constante escuta de Deus, que aceita os apelos de Deus e que lhes responde com a obedi\u00eancia total. Essa \u201centrega\u201d a Deus \u00e9 fonte de Vida e de b\u00ean\u00e7\u00e3o.<\/p>\n\n\n\n<p><strong>A Ep\u00edstola de S\u00e3o Paulo aos Romanos,<\/strong>&nbsp;lembra aos crentes que Deus os ama com um amor imenso e eterno. A melhor prova desse amor \u00e9 Jesus Cristo, o Filho amado de Deus que morreu para ensinar ao homem o caminho da vida verdadeira. Sendo assim, o crist\u00e3o nada tem a temer e deve enfrentar a vida com serenidade e esperan\u00e7a.<\/p>\n\n\n\n<p><strong>O Evangelho de S\u00e3o Marcos, <\/strong>relata a transfigura\u00e7\u00e3o de Jesus. Marcos, o evangelista, apresenta-nos uma catequese sobre Jesus, o Filho amado de Deus, que vai concretizar o seu projeto libertador em favor dos homens atrav\u00e9s do dom da vida. Aos disc\u00edpulos, desanimados e assustados, Jesus diz: o caminho do dom da vida n\u00e3o conduz ao fracasso, mas \u00e0 Vida plena e definitiva. Segui-o, v\u00f3s tamb\u00e9m.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\"><strong><u>Evangelho de Nosso Senhor Jesus Cristo Segundo S\u00e3o Marcos<\/u><\/strong><\/h2>\n\n\n\n<p>Naquele tempo, Jesus tomou consigo Pedro, Tiago e Jo\u00e3o e subiu s\u00f3 com eles para um lugar retirado num alto monte e transfigurou-Se diante deles. As suas vestes tornaram-se resplandecentes, de tal brancura que nenhum lavadeiro sobre a terra as poderia assim branquear. Apareceram-lhes Mois\u00e9s e Elias, conversando com Jesus. Pedro tomou a palavra e disse a Jesus: \u00abMestre, como \u00e9 bom estarmos aqui! Fa\u00e7amos tr\u00eas tendas: uma para Ti, outra para Mois\u00e9s, outra para Elias\u00bb. N\u00e3o sabia o que dizia, pois estavam atemorizados. Veio ent\u00e3o uma nuvem que os cobriu com a sua sombra, e da nuvem fez-se ouvir uma voz: \u00abEste \u00e9 o meu Filho muito amado: escutai-O\u00bb. De repente, olhando em redor, n\u00e3o viram mais ningu\u00e9m, a n\u00e3o ser Jesus, sozinho com eles. Ao descerem do monte, Jesus ordenou-lhes que n\u00e3o contassem a ningu\u00e9m o que tinham visto, enquanto o Filho do homem n\u00e3o ressuscitasse dos mortos. Eles guardaram a recomenda\u00e7\u00e3o, mas perguntavam entre si o que seria ressuscitar dos mortos. <br><strong>Palavra da Salva\u00e7\u00e3o<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"391\" height=\"213\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/02\/38.jpg\" alt=\"\" class=\"wp-image-2260\" style=\"width:525px;height:auto\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/02\/38.jpg 391w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/02\/38-300x163.jpg 300w\" sizes=\"(max-width: 391px) 100vw, 391px\" \/><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<p><strong><u>(Mensagem do D. Ant\u00f3nio Moiteiro\/Quaresma 2024)<\/u><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Somos pedras vivas<\/strong><\/h2>\n\n\n\n<p>1. <em>A indulg\u00eancia Plen\u00e1ria pr\u00f3pria do jubileu<\/em> \u00e9 concedida nas condi\u00e7\u00f5es habituais (Confiss\u00e3o sacramental, Comunh\u00e3o eucar\u00edstica e ora\u00e7\u00e3o pelas inten\u00e7\u00f5es do Sumo Pont\u00edfice) aos fi\u00e9is verdadeiramente arrependidos e movidos pela caridade, a qual tamb\u00e9m pode ser aplicada como sufr\u00e1gio \u00e0s almas dos fi\u00e9is que se encontram no Purgat\u00f3rio, se visitarem a mesma igreja Catedral em forma de peregrina\u00e7\u00e3o e a\u00ed devotamente cumprirem os ritos jubilares, ou ent\u00e3o se durante um conveniente espa\u00e7o de tempo se entregarem a piedosa medita\u00e7\u00e3o, concluindo com a Ora\u00e7\u00e3o Dominical, S\u00edmbolo da F\u00e9 e invoca\u00e7\u00e3o da Bem-aventurada Virgem Maria.<\/p>\n\n\n\n<p>2. <em>Retiro quaresmal<\/em>,nos dias 16 e 17 de mar\u00e7o, na Casa Diocesana de Albergaria, em sintonia com a tem\u00e1tica do Congresso Eucar\u00edstico Nacional \u00ab<em>Partilhar o P\u00e3o, alimentar a Esperan\u00e7a<\/em>\u00bb. Queremos que seja um tempo de mais ora\u00e7\u00e3o e partilha de vida e de encontro com Deus.&nbsp;<\/p>\n\n\n\n<p>3. As <em>24 horas para o Senhor<\/em>. Nos dias 8 e 9 de mar\u00e7o celebramos, a pedido do Papa Francisco, vinte e quatro horas de ora\u00e7\u00e3o intensa e adora\u00e7\u00e3o ao Sant\u00edssimo. Este ano seria muito importante que nos tempos de ora\u00e7\u00e3o e adora\u00e7\u00e3o utiliz\u00e1ssemos as catequeses \u201c<em>Redescobrir as origens e o sentido da celebra\u00e7\u00e3o da Eucaristia<\/em>\u201d, como forma de prepararmos o pr\u00f3ximo Congresso Eucar\u00edstico Nacional. Temos acesso a estas catequeses no site que foi enviado a todos os sacerdotes pelo nosso Gabinete de Comunica\u00e7\u00e3o.<\/p>\n\n\n\n<p>4. A <em>Ren\u00fancia Quaresmal<\/em> ser\u00e1 destinada \u00e0 diocese de Luena, em Angola, e ao Fundo de Emerg\u00eancia Social, da C\u00e1ritas Diocesana. As raz\u00f5es do destino da Ren\u00fancia Quaresmal prendem-se com os la\u00e7os que o Servi\u00e7o Diocesano de A\u00e7\u00e3o Mission\u00e1ria tem com a diocese angolana e a preocupa\u00e7\u00e3o com os pobres, os imigrantes e os que n\u00e3o t\u00eam condi\u00e7\u00f5es de vida digna e que todos os dias batem \u00e0 porta da nossa Caritas, e dos grupos Socio-caritativos e Vicentinos. Para muitos dos nossos irm\u00e3os, a vida tem sido muito dura, fruto das desigualdades sociais que se v\u00e3o acentuando na nossa sociedade.<\/p>\n\n\n\n<p>5. No pr\u00f3ximo dia 10 de mar\u00e7o, todos somos chamados, atrav\u00e9s da <em>participa\u00e7\u00e3o c\u00edvica no ato de votar<\/em>, a contribuir para a constru\u00e7\u00e3o de uma sociedade mais justa e menos desigual. H\u00e1 valores dos quais n\u00e3o podemos prescindir, como sejam o respeito pela vida humana, uma sociedade onde as injusti\u00e7as, as desigualdades sociais e salariais, a corrup\u00e7\u00e3o, os lucros desmedidos de alguns, \u00e0 custa de tantos outros, n\u00e3o tenham lugar nos v\u00e1rios campos da vida social. Votar n\u00e3o \u00e9 apenas um direito, mas sim uma exig\u00eancia que nasce da f\u00e9 crist\u00e3 e que est\u00e1 na Doutrina Social da Igreja. Se queremos uma sociedade mais justa e fraterna devemos contribuir com o nosso voto. Esta pode ser tamb\u00e9m uma pr\u00e1tica de convers\u00e3o pr\u00f3pria da Quaresma.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">S\u00ednodo: em Portugal as dioceses est\u00e3o em caminho de reflex\u00e3o<\/h2>\n\n\n\n<p>Durante esta semana est\u00e1 em Portugal o cardeal Jean-Claude Hollerich, Relator Geral da XVI Assembleia Geral do S\u00ednodo. Segundo nota da Confer\u00eancia Episcopal Portuguesa (CEP) o arcebispo do Luxemburgo est\u00e1 a orientar o retiro de Quaresma dos bispos portugueses, que decorre em F\u00e1tima de 19 a 23 de fevereiro. Entretanto, as dioceses portuguesas est\u00e3o em plena fase de reflex\u00e3o para a segunda sess\u00e3o do S\u00ednodo que ter\u00e1 lugar em Roma de 2 a 27 de outubro. Um processo de trabalho proposto pela Secretaria Geral do S\u00ednodo a 12 de dezembro e que tem a seguinte quest\u00e3o orientadora: \u201cComo ser Igreja sinodal em miss\u00e3o?\u201d Em Portugal, o Conselho Permanente da CEP enviou a 9 de janeiro orienta\u00e7\u00f5es para as dioceses pedindo que a reflex\u00e3o incidisse, em particular, nos cap\u00edtulos 8-12, 16 e 18 do Relat\u00f3rio de S\u00edntese da XVI Assembleia Geral do S\u00ednodo dos Bispos. Recordemos que os participantes na primeira sess\u00e3o do S\u00ednodo, para al\u00e9m do Relat\u00f3rio de S\u00edntese, publicaram tamb\u00e9m uma Carta ao Povo de Deus, na qual pedem que todos devem ser escutados.<\/p>\n\n\n\n<p><strong>Dioceses em caminho<\/strong><\/p>\n\n\n\n<p>A Rede Sinodal em Portugal tem vindo a acompanhar o que cada diocese est\u00e1 a fazer. Com a informa\u00e7\u00e3o disponibilizada por este site revelamos aqui, a t\u00edtulo de exemplo, os percursos de Vila Real, Porto, Lisboa e Aveiro. Estas dioceses foram as primeiras a ser citadas nas publica\u00e7\u00f5es regulares que a Rede Sinodal em Portugal tem vindo a fazer desde dia 6 de janeiro.<\/p>\n\n\n\n<p>Segundo a comiss\u00e3o&nbsp;sinodal&nbsp;daquela diocese esses delegados reuniram-se em assembleia em janeiro e est\u00e3o agora no terreno a reunir os agentes de pastoral, informa a Rede Sinodal em Portugal.<\/p>\n\n\n\n<p>Neste curto apanhado de s\u00edntese sobre o caminho sinodal nas dioceses portuguesas, revelamos que a comiss\u00e3o sinodal da diocese de Aveiro est\u00e1 a estudar o Relat\u00f3rio de S\u00edntese, com a \u201cpreocupa\u00e7\u00e3o maior de n\u00e3o deixar morrer o dinamismo\u00a0sinodal\u201d. Nesta fase de prepara\u00e7\u00e3o para a segunda sess\u00e3o da Assembleia do S\u00ednodo \u201cfoi enviado aos arciprestes um conjunto de perguntas para serem analisadas\u201d e cujo \u201ceco ser\u00e1 dado em finais de fevereiro\u201d. Depois desta fase, \u201ca comiss\u00e3o diocesana far\u00e1 a sua reflex\u00e3o considerando os contributos\u201d e o \u201cconselho diocesano de pastoral tamb\u00e9m se ir\u00e1 debru\u00e7ar sobre a sinodalidade\u201d, revela a Rede Sinodal.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"750\" height=\"422\" data-id=\"2262\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/02\/39.jpg\" alt=\"\" class=\"wp-image-2262\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/02\/39.jpg 750w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/02\/39-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"750\" height=\"422\" data-id=\"2261\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/02\/40.jpg\" alt=\"\" class=\"wp-image-2261\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/02\/40.jpg 750w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2024\/02\/40-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Sexta-feira Santa: um dia de solidariedade universal com a Igreja de Jerusal\u00e9m<\/h2>\n\n\n\n<p>Car\u00edssimas amigas, car\u00edssimos amigos, que o Senhor vos d\u00ea a paz.<\/p>\n\n\n\n<p>1.Depois de termos vivido mais de dois anos de incerteza por causa da Covid e de termos nos iludido com o retorno aparente da normalidade, subitamente no dia 7 de outubro fomos pegos de surpresa pela eclos\u00e3o de uma nova guerra na Terra Santa, que, al\u00e9m de causar milhares de mortes, bloqueou mais uma vez o fluxo de peregrinos, tirou as nossas crian\u00e7as das escola durante longos per\u00edodos e deixou muitos dos nossos crist\u00e3os na Terra Santa sem trabalho, especialmente em Bel\u00e9m e na Palestina, mas tamb\u00e9m na Cidade Antiga de Jerusal\u00e9m e em Israel.<\/p>\n\n\n\n<p>2. Nesta situa\u00e7\u00e3o sentimos a necessidade da proximidade e da solidariedade dos crist\u00e3os de todo o mundo. Antes de tudo atrav\u00e9s da ora\u00e7\u00e3o, porque estamos convencidos de que s\u00f3 a a\u00e7\u00e3o da gra\u00e7a de Deus pode mudar os cora\u00e7\u00f5es e orient\u00e1-los para o di\u00e1logo, a reconcilia\u00e7\u00e3o e a paz. Depois, solidariedade e proximidade atrav\u00e9s da peregrina\u00e7\u00e3o. Precisamos muito tamb\u00e9m &nbsp;da proximidade e da solidariedade atrav\u00e9s da partilha de recursos econ\u00f4micos.<\/p>\n\n\n\n<p>3. Como frades da Cust\u00f3dia da Terra Santa \u00e9 nossa miss\u00e3o, segundo o mandato da Santa S\u00e9, cuidar dos lugares santos, habit\u00e1-los e torn\u00e1-los lugares de ora\u00e7\u00e3o, ser acolhedores para com os fi\u00e9is locais e para com os peregrinos, e tamb\u00e9m realizar obras educativas como escolas, obras sociais como lares para idosos e fam\u00edlias jovens, cl\u00ednicas e ambulat\u00f3rios, obras de promo\u00e7\u00e3o humana atrav\u00e9s da cria\u00e7\u00e3o de empregos.<\/p>\n\n\n\n<p>4. A Coleta da Sexta-Feira Santa serve para cobrir parte destes custos, gra\u00e7as \u00e0 generosidade dos fi\u00e9is de todo o mundo, gra\u00e7as \u00e0 sua generosidade.<\/p>\n\n\n\n<p>5. Nesta ocasi\u00e3o, n\u00f3s, frades da Cust\u00f3dia da Terra Santa, tornamo-nos mendicantes e recorremos a todos para que a Sexta-feira Santa seja um dia de solidariedade universal, um dia em que os crist\u00e3os de todo o mundo ajudem concretamente a Igreja m\u00e3e de Jerusal\u00e9m, que neste momento tem extrema necessidade de ajuda.<\/p>\n\n\n\n<p>6. Por favor, abra o seu cora\u00e7\u00e3o e ajude-nos de acordo com as suas possibilidades, para que tamb\u00e9m n\u00f3s possamos continuar a cuidar desta Terra Santa e dos seus filhos.<\/p>\n\n\n\n<div style=\"height:65px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>II Domingo da Quaresma \u2013\u00a0Ano BMensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto Neste II domingo da Quaresma a liturgia apresenta o relato da Transfigura\u00e7\u00e3o do Senhor. Na verdade, mesmo antes da Paix\u00e3o e Morte Jesus faz antever aos &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2024\/02\/25\/novos-ventos-25-de-fevereiro\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[32,8],"tags":[34,33],"class_list":["post-2259","post","type-post","status-publish","format-standard","hentry","category-novos-ventos","category-oracao","tag-boletim","tag-novos-ventos"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=2259"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2259\/revisions"}],"predecessor-version":[{"id":2263,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/2259\/revisions\/2263"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=2259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=2259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=2259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}