{"id":1441,"date":"2022-03-20T10:30:26","date_gmt":"2022-03-20T10:30:26","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=1441"},"modified":"2022-03-20T10:30:30","modified_gmt":"2022-03-20T10:30:30","slug":"novos-ventos-20-de-marco","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2022\/03\/20\/novos-ventos-20-de-marco\/","title":{"rendered":"Novos Ventos &#8211; 20 de Mar\u00e7o"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"vii-domingo-do-tempo-comum-ano-c\">III\u00a0<strong>Domingo da Quaresma<\/strong>\u00a0\u2013\u00a0<strong>Ano C<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mensagem-dominical-das-paroquias-de-torreira-e-sao-jacinto\"><strong>Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto<\/strong><\/h2>\n\n\n\n<p>Neste III Domingo da Quaresma o evangelista Lucas apresenta a par\u00e1bola da Figueira est\u00e9ril. O senhor da vinha veio ao campo, afim de colher os seus frutos. Como a \u00e1rvore n\u00e3o dava frutos o dono disse ao vinhateiro para cortar a figueira. O vinhateiro disse ao senhor que a deixasse ficar que iria cuidar dela e trata-la para ver se esta daria frutos.<\/p>\n\n\n\n<p>O Senhor da vinha \u00e9 Deus que espera encontrar frutos em cada um de n\u00f3s, frutos esses que passam por uma convers\u00e3o interior. Muitas vezes, permanecemos nos nossos erros e pecados fechando o nosso cora\u00e7\u00e3o ao Senhor. Tal como o vinhateiro procura cuidar e tratar do campo e da figueira para que possa dar fruto, assim procede Jesus connosco pela sua grande miseric\u00f3rdia e um Amor infinito ao dar a Sua Vida por n\u00f3s. \u00c9 como se Jesus nos dissesse \u201cvou escavar o seu cora\u00e7\u00e3o e fortalecer com o Meu Amor. <strong><\/strong><\/p>\n\n\n\n<p><strong>A leitura do livro do \u00caxodo, <\/strong>&nbsp;&nbsp;fala-nos do Deus que n\u00e3o suporta as injusti\u00e7as e as arbitrariedades e que est\u00e1 sempre presente naqueles que lutam pela liberta\u00e7\u00e3o. \u00c9 esse Deus libertador que exige de n\u00f3s uma luta permanente contra tudo aquilo que nos escraviza e que impede a manifesta\u00e7\u00e3o da vida plena.<\/p>\n\n\n\n<p><strong>A<\/strong> <strong>Leitura de S\u00e3o Paulo aos Cor\u00edntios, <\/strong>\u00a0avisa-nos que o cumprimento de ritos externos e vazios n\u00e3o \u00e9 importante; o que \u00e9 importante \u00e9 a ades\u00e3o verdadeira a Deus, a vontade de aceitar a sua proposta de salva\u00e7\u00e3o e de viver com Ele numa comunh\u00e3o \u00edntima.<strong>O Evangelho de S\u00e3o Lucas,<\/strong> cont\u00e9m um convite a uma transforma\u00e7\u00e3o radical da exist\u00eancia, a uma mudan\u00e7a de mentalidade, a um recentrar a vida de forma que Deus e os seus valores passem a ser a nossa prioridade fundamental. Se isso n\u00e3o acontecer, diz Jesus, a nossa vida ser\u00e1 cada vez mais controlada pelo ego\u00edsmo que leva \u00e0 morte.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><u>Evangelho de Nosso Senhor Jesus Cristo Segundo S\u00e3o Lucas<\/u><\/strong><\/h3>\n\n\n\n<p>Naquele tempo, vieram contar a Jesus que Pilatos mandara derramar o sangue de certos galileus, juntamente com o das v\u00edtimas que imolavam. Jesus respondeu-lhes: \u00abJulgais que, por terem sofrido tal castigo, esses galileus eram mais pecadores do que todos os outros galileus? Eu digo-vos que n\u00e3o. E se n\u00e3o vos arrependerdes, morrereis todos do mesmo modo. E aqueles dezoito homens, que a torre de Silo\u00e9, ao cair, atingiu e matou?<br>Julgais que eram mais culpados do que todos os outros habitantes de Jerusal\u00e9m? Eu digo-vos que n\u00e3o. E se n\u00e3o vos arrependerdes, morrereis todos de modo semelhante. Jesus disse ent\u00e3o a seguinte par\u00e1bola: \u00abCerto homem tinha uma figueira plantada na sua vinha. Foi procurar os frutos que nela houvesse, mas n\u00e3o os encontrou. Disse ent\u00e3o ao vinhateiro: \u2018H\u00e1 tr\u00eas anos que venho procurar frutos nesta figueira e n\u00e3o os encontro. Deves cort\u00e1-la. Porque h\u00e1-de estar ela a ocupar inutilmente a terra?\u2019 Mas o vinhateiro respondeu-lhe: \u2018Senhor, deixa-a ficar ainda este ano, que eu, entretanto, vou cavar-lhe em volta e deitar-lhe adubo. Talvez venha a dar frutos. Se n\u00e3o der, mand\u00e1-la-\u00e1s cortar no pr\u00f3ximo ano\u00bb.<strong> Palavra do Senhor<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<p><strong><u>&nbsp;Palavra de Vida \u2013 Mar\u00e7o<\/u><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u201cPerdoai-nos as nossas ofensas, assim como n\u00f3s perdoamos a quem nos tem ofendido.\u201d&nbsp;<\/strong><em>(Mt 6,12)<\/em><\/h3>\n\n\n\n<p>Por vezes, as pessoas com quem vivemos \u2013 na fam\u00edlia, no bairro, no local de trabalho ou de estudo \u2013 podem ter sido injustas para connosco e sentimos dificuldade em voltar a ter um relacionamento positivo. O que fazer? \u00c9 nestas situa\u00e7\u00f5es que podemos pedir a gra\u00e7a de imitar o Pai:&nbsp;<\/p>\n\n\n\n<p>\u00ab[\u2026] Levantemo-nos de manh\u00e3 com uma \u201camnistia\u201d completa no cora\u00e7\u00e3o, com aquele amor que tudo desculpa, que sabe aceitar o outro tal como ele \u00e9, com os seus limites, as suas dificuldades, precisamente como faria uma m\u00e3e com o seu filho que erra: desculpa-o sempre, perdoa-lhe sempre, tem sempre esperan\u00e7a nele\u2026 Quando estamos com uma pessoa, vejamo-la com \u201colhos novos\u201d, como se nunca tivesse cometido aqueles erros. Recomecemos sempre, sabendo que Deus n\u00e3o s\u00f3 perdoa, mas esquece: \u00e9 esta a medida que Ele nos pede tamb\u00e9m\u00bb <sup>[1]<\/sup>.&nbsp;\u00c9 uma meta elevada, mas podemos chegar l\u00e1 com a ajuda da ora\u00e7\u00e3o confiante.&nbsp;<\/p>\n\n\n\n<p><em>Letizia Magri<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"810\" height=\"324\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/42.png\" alt=\"\" class=\"wp-image-1442\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/42.png 810w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/42-300x120.png 300w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/42-768x307.png 768w\" sizes=\"(max-width: 810px) 100vw, 810px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Em 25 de mar\u00e7o, o Papa consagrar\u00e1 a R\u00fassia e a Ucr\u00e2nia ao Imaculado Cora\u00e7\u00e3o de Maria<\/h3>\n\n\n\n<p>&#8220;Na sexta-feira, 25 de mar\u00e7o, durante a Celebra\u00e7\u00e3o da Penit\u00eancia que presidir\u00e1 \u00e0s 17h na Bas\u00edlica de S\u00e3o Pedro, o Papa Francisco consagrar\u00e1 a R\u00fassia e a Ucr\u00e2nia ao Imaculado Cora\u00e7\u00e3o de Maria. O mesmo ato ser\u00e1 realizado, no mesmo dia, em F\u00e1tima pelo esmoleiro do Papa, cardeal Konrad Krajewski, enviado do Santo Padre.&#8221;<\/p>\n\n\n\n<p>A not\u00edcia foi dada, numa nota, pelo diretor da Sala de Imprensa da Santa S\u00e9, Matteo Bruni. O dia da Festa da Anuncia\u00e7\u00e3o do Senhor foi escolhido para a consagra\u00e7\u00e3o. Nossa Senhora, na apari\u00e7\u00e3o de 13 de julho de 1917, em F\u00e1tima, pediu a consagra\u00e7\u00e3o da R\u00fassia ao Seu Imaculado Cora\u00e7\u00e3o, afirmando que, se este pedido n\u00e3o fosse atendido, a R\u00fassia espalharia &#8220;seus erros pelo mundo, promovendo guerras e persegui\u00e7\u00f5es \u00e0 Igreja&#8221;. &#8220;Os bons&#8221;, acrescentou, &#8220;ser\u00e3o martirizados, o Santo Padre sofrer\u00e1 muito, v\u00e1rias na\u00e7\u00f5es ser\u00e3o destru\u00eddas&#8221;. Depois das apari\u00e7\u00f5es de F\u00e1tima houve v\u00e1rios atos de consagra\u00e7\u00e3o ao Imaculado Cora\u00e7\u00e3o de Maria: Pio XII, em 31 de outubro de 1942, consagrou o mundo inteiro, e em 7 de julho de 1952, consagrou os povos da R\u00fassia ao Imaculado Cora\u00e7\u00e3o de Maria na Carta Apost\u00f3lica Sacro vergente anno:<\/p>\n\n\n\n<p>Depois, para responder mais plenamente aos pedidos de Nossa Senhora, quis explicitar durante o Ano Santo da Reden\u00e7\u00e3o o ato de entrega de 7 de Junho de 1981, repetido em F\u00e1tima a 13 de maio de 1982. Em mem\u00f3ria do Fiat pronunciado por Maria no momento da Anuncia\u00e7\u00e3o, em 25 de mar\u00e7o de 1984, na Pra\u00e7a S\u00e3o Pedro, em uni\u00e3o espiritual com todos os bispos do mundo, previamente &#8220;convocados&#8221;, Jo\u00e3o Paulo II confiou todos os povos ao Imaculado Cora\u00e7\u00e3o de Maria:<\/p>\n\n\n\n<p><em>E por isso, \u00f3 M\u00e3e dos homens e dos povos, Tu que conheces todos os seus sofrimentos e todas as suas esperan\u00e7as, Tu que sentes maternalmente todas as lutas entre o bem e o mal, entre a luz e as trevas, que abalam o mundo contempor\u00e2neo, acolhe o nosso grito que, movido pelo Esp\u00edrito Santo, dirigimos diretamente ao teu Cora\u00e7\u00e3o: abra\u00e7a com amor de M\u00e3e e Serva do Senhor, este nosso mundo humano, que Te confiamos e consagramos, cheio de inquietude pela sorte terrena e eterna dos homens e dos povos. De modo especial Te confiamos e consagramos aqueles homens e na\u00e7\u00f5es que t\u00eam necessidade particular desta entrega e consagra\u00e7\u00e3o.<\/em><\/p>\n\n\n\n<p>Em junho do ano 2000, a Santa S\u00e9 revelou a terceira parte do segredo de F\u00e1tima e o ent\u00e3o arcebispo Tarcisio Bertone, secret\u00e1rio da Congrega\u00e7\u00e3o para a Doutrina da F\u00e9, sublinhou que irm\u00e3 L\u00facia, numa carta de 1989, tinha confirmado pessoalmente que este ato de consagra\u00e7\u00e3o solene e universal correspondia ao que Nossa Senhora queria: &#8220;Sim, foi feito&#8221;, escreveu a vidente, &#8220;como Nossa Senhora havia pedido, em 25 de mar\u00e7o de 1984&#8221;.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img decoding=\"async\" width=\"750\" height=\"422\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/42.jpg\" alt=\"\" class=\"wp-image-1443\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/42.jpg 750w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/42-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure><\/div>\n\n\n\n<div style=\"height:61px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>III\u00a0Domingo da Quaresma\u00a0\u2013\u00a0Ano C Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto Neste III Domingo da Quaresma o evangelista Lucas apresenta a par\u00e1bola da Figueira est\u00e9ril. O senhor da vinha veio ao campo, afim de colher os seus frutos. &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2022\/03\/20\/novos-ventos-20-de-marco\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[32,8],"tags":[34,33],"class_list":["post-1441","post","type-post","status-publish","format-standard","hentry","category-novos-ventos","category-oracao","tag-boletim","tag-novos-ventos"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1441","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=1441"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1441\/revisions"}],"predecessor-version":[{"id":1444,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1441\/revisions\/1444"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=1441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=1441"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=1441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}