{"id":1426,"date":"2022-03-06T10:46:25","date_gmt":"2022-03-06T10:46:25","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=1426"},"modified":"2022-03-06T10:46:30","modified_gmt":"2022-03-06T10:46:30","slug":"novos-ventos-06-de-marco","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2022\/03\/06\/novos-ventos-06-de-marco\/","title":{"rendered":"Novos Ventos &#8211; 06 de Mar\u00e7o"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"vii-domingo-do-tempo-comum-ano-c\">I <strong>Domingo da Quaresma<\/strong>\u00a0\u2013\u00a0<strong>Ano C<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mensagem-dominical-das-paroquias-de-torreira-e-sao-jacinto\"><strong>Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto<\/strong><\/h2>\n\n\n\n<p>Neste I Domingo da Quaresma a liturgia apresenta-nos Jesus no deserto a ser tentado pelo diabo. Depois de Jesus estar quarenta dias no deserto sentiu fome, ent\u00e3o diabo disse-lhe: \u00abSe \u00e9s Filho de Deus, manda a esta pedra que se transforme em p\u00e3o\u00bb. A primeira tenta\u00e7\u00e3o est\u00e1 relacionada com o materialismo, obter os bens com o menor grau de esfor\u00e7o \u201cSe \u00e9s Filho de Deus manda\u2026\u201d. A resposta que Jesus d\u00e1 permite perceber que n\u00e3o devemos apenas focar a nossa vida nos bens materiais, no alimento, nas roupas de marca, no carro de luxo, no telem\u00f3vel de gama, mas \u00e9 necess\u00e1rio alimentar-se com outro tipo de alimento que nos revigora o interior \u00abN\u00e3o s\u00f3 de p\u00e3o vive o homem, mas de toda a Palavra que sai da boca de Deus\u00bb. A Quaresma \u00e9 o tempo por excel\u00eancia para nutrir-me mais da Palavra de Deus.<strong><\/strong><\/p>\n\n\n\n<p><strong>A leitura do livro do Deuteron\u00f3mio, <\/strong>convida-nos a eliminar os falsos deuses em quem \u00e0s vezes apostamos tudo e a fazer de Deus a nossa refer\u00eancia fundamental. Alerta-nos, na mesma l\u00f3gica, contra a tenta\u00e7\u00e3o do orgulho e da autossufici\u00eancia, que nos levam a caminhos de ego\u00edsmo e de desumanidade, de desgra\u00e7a e de morte.<\/p>\n\n\n\n<p><strong>A<\/strong> <strong>Leitura de S\u00e3o Paulo aos Romanos, <\/strong>&nbsp;convida-nos a prescindir de uma atitude arrogante e autossuficiente em rela\u00e7\u00e3o \u00e0 salva\u00e7\u00e3o que Deus nos oferece: a salva\u00e7\u00e3o n\u00e3o \u00e9 uma conquista nossa, mas um dom gratuito de Deus. \u00c9 preciso, pois, \u201cconverter-se\u201d a Jesus, isto \u00e9, reconhec\u00ea-l\u2019O como o \u201cSenhor\u201d e acolher no cora\u00e7\u00e3o a salva\u00e7\u00e3o que, em Jesus, Deus nos prop\u00f5e.<\/p>\n\n\n\n<p><strong>O Evangelho de S\u00e3o Lucas, <\/strong>\u00a0apresenta-nos uma catequese sobre as op\u00e7\u00f5es de Jesus. Lucas sugere que Jesus recusou radicalmente um caminho de materialismo, de poder, de \u00eaxito f\u00e1cil, pois o plano de Deus n\u00e3o passava pelo ego\u00edsmo, mas pela partilha; n\u00e3o passava pelo autoritarismo, mas pelo servi\u00e7o; n\u00e3o passava por manifesta\u00e7\u00f5es espetaculares que impressionam as massas, mas por uma proposta de vida plena, apresentada com simplicidade e amor. \u00c9 claro que \u00e9 esse caminho que \u00e9 sugerido aos que seguem Jesus.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong><u>Evangelho de Nosso Senhor Jesus Cristo Segundo S\u00e3o Lucas<\/u><\/strong><\/h3>\n\n\n\n<p>Naquele tempo, Jesus, cheio do Esp\u00edrito Santo, retirou-Se das margens do Jord\u00e3o. Durante quarenta dias, esteve no deserto, conduzido pelo Esp\u00edrito, e foi tentado pelo diabo. Nesses dias n\u00e3o comeu nada e, passado esse tempo, sentiu fome. O diabo disse-lhe: \u00abSe \u00e9s Filho de Deus, manda a esta pedra que se transforme em p\u00e3o\u00bb. Jesus respondeu-lhe: \u00abEst\u00e1 escrito: \u2018Nem s\u00f3 de p\u00e3o vive o homem\u2019\u00bb. O diabo levou-O a um lugar alto e mostrou-Lhe num instante todos os reinos da terra e disse-Lhe: \u00abEu Te darei todo este poder e a gl\u00f3ria destes reinos, porque me foram confiados e os dou a quem eu quiser. Se Te prostrares diante de mim, tudo ser\u00e1 teu\u00bb. Jesus respondeu-lhe: \u00abEst\u00e1 escrito: \u2018Ao Senhor teu Deus adorar\u00e1s, s\u00f3 a Ele prestar\u00e1s culto\u2019\u00bb. Ent\u00e3o o dem\u00f3nio levou-O a Jerusal\u00e9m, colocou-O sobre o pin\u00e1culo do Templo e disse-Lhe: \u00abSe \u00e9s Filho de Deus, atira-te daqui abaixo, porque est\u00e1 escrito: \u2018Ele dar\u00e1 ordens aos seus Anjos a teu respeito, para que te guardem\u2019; e ainda: \u2018Na palma das m\u00e3os te levar\u00e3o, para que n\u00e3o tropeces em alguma pedra\u2019\u00bb. Jesus respondeu-lhe: \u00abEst\u00e1 mandado: \u2018N\u00e3o tentar\u00e1s o Senhor teu Deus\u2019\u00bb. Ent\u00e3o o diabo, tendo terminado toda a esp\u00e9cie de tenta\u00e7\u00e3o, retirou-se da presen\u00e7a de Jesus, at\u00e9 certo tempo.<\/p>\n\n\n\n<p><strong>Palavra do Senhor<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<p><strong><u>&nbsp;Palavra de Vida \u2013 Mar\u00e7o<\/u><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u201cPerdoai-nos as nossas ofensas, assim como n\u00f3s perdoamos a quem nos tem ofendido.\u201d&nbsp;<\/strong><em>(Mt 6,12)<\/em><\/h3>\n\n\n\n<p>A palavra de vida deste m\u00eas faz parte da ora\u00e7\u00e3o que Jesus ensinou aos seus disc\u00edpulos, o Pai Nosso. \u00c9 uma ora\u00e7\u00e3o profundamente radicada na tradi\u00e7\u00e3o hebraica. Tamb\u00e9m os hebreus chamavam e chamam a Deus \u201cPai nosso\u201d.&nbsp;<\/p>\n\n\n\n<p>Numa primeira leitura, as palavras desta frase deixam-nos perplexos: podemos pedir a Deus que cancele as nossas ofensas, como sugere o texto grego, com a mesma medida com que n\u00f3s pr\u00f3prios somos capazes de o fazer com quem tem alguma falta contra n\u00f3s? A nossa capacidade de perd\u00e3o \u00e9 sempre limitada, superficial, condicionada.<\/p>\n\n\n\n<p>Se Deus nos tratasse com a nossa medida, seria uma verdadeira condena\u00e7\u00e3o!<\/p>\n\n\n\n<p><em>Letizia Magri<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"752\" height=\"376\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/34.jpg\" alt=\"\" class=\"wp-image-1427\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/34.jpg 752w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/34-300x150.jpg 300w\" sizes=\"(max-width: 752px) 100vw, 752px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">O Papa: Deus, escute as ora\u00e7\u00f5es dos que fogem do barulho das armas na Ucr\u00e2nia<\/h3>\n\n\n\n<p>&#8220;Senhor, escutai a ora\u00e7\u00e3o de quantos confiam em V\u00f3s, sobretudo dos mais humildes, dos mais provados, daqueles que sofrem e fogem sob o estrondo das armas. Colocai de novo a paz nos cora\u00e7\u00f5es, concedei aos nossos dias a vossa paz. Am\u00e9m&#8221;. Nos mais de duzentos caracteres do tu\u00edte \u2013 o instrumento da m\u00eddia social que permite alcan\u00e7ar milh\u00f5es de usu\u00e1rios ao mesmo tempo &#8211; Francisco condensa toda a sua dor pela devasta\u00e7\u00e3o que est\u00e1 devastando a Ucr\u00e2nia nestas horas. Ap\u00f3s apelos contra as armas ou de ajuda \u00e0 popula\u00e7\u00e3o, atrav\u00e9s de cita\u00e7\u00f5es de passagens da&nbsp;<em>Fratelli tutti<\/em>, para sua mensagem de hoje na conta @Pontifex em dez idiomas, o Papa formula uma ora\u00e7\u00e3o. Acompanhada de uma imagem perfil do Pont\u00edfice com a cabe\u00e7a curvada no ato de rezar, a ora\u00e7\u00e3o \u00e9 especialmente dedicada \u00e0queles que agora est\u00e3o &#8220;sofrendo sob os bombardeios&#8221;, como ele disse ontem na audi\u00eancia geral.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Oito dias de guerra e milhares de mortos<\/h4>\n\n\n\n<p>Em seu comunicado di\u00e1rio, Sviatoslav Shevchuk, arcebispo mor da Igreja greco-cat\u00f3lica ucraniana, lembra que hoje a Ucr\u00e2nia entrou na segunda semana desta &#8220;terr\u00edvel guerra&#8221;, e que ontem \u00e0 noite se mostrou em todo o seu horror. Os olhos de pessoas de todo o mundo, de todas as Igrejas, religi\u00f5es e denomina\u00e7\u00f5es, est\u00e3o voltados para a capital ucraniana. Uma unidade concretizada pela ora\u00e7\u00e3o comum pela paz na Bas\u00edlica de Santa Sofia dos representantes de todas as igrejas e organiza\u00e7\u00f5es religiosas ucranianas. &#8220;Que o Deus da paz, em quem confiamos, nos d\u00ea a possibilidade de defender esta paz, esperando n\u2019Ele para n\u00e3o vacilar&#8221;, foi a ora\u00e7\u00e3o do arcebispo greco-cat\u00f3lico. E concluiu com uma sincera invoca\u00e7\u00e3o ao Senhor: &#8220;Rogamos-Te, Deus, na Tua sabedoria, que detenhas a guerra!&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"750\" height=\"422\" data-id=\"1428\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/35.jpg\" alt=\"\" class=\"wp-image-1428\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/35.jpg 750w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/35-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1000\" height=\"563\" data-id=\"1429\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/36.jpg\" alt=\"\" class=\"wp-image-1429\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/36.jpg 1000w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/36-300x169.jpg 300w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/03\/36-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">&#8220;Estamos vivendo cada dia como se fosse uma P\u00e1scoa&#8221;, afirma padre brasileiro em Kiev<\/h3>\n\n\n\n<p>\u201cEstamos vivendo cada dia como se fosse uma P\u00e1scoa, como se hoje tiv\u00e9ssemos que morrer\u201d: palavras do sacerdote brasileiro Lucas Perozzi Jorge, que vive em Kiev desde 2004. Do caminho necatecumenal, Pe. Lucas atualmente \u00e9 vig\u00e1rio da Igreja da Dormi\u00e7\u00e3o da Sant\u00edssima Virgem Maria. Ele e mais 35 pessoas, entre membros da comunidade e paroquianos que pediram abrigo, est\u00e3o vivendo dentro da Igreja, numa parte segura que fica no subsolo. Por enquanto, n\u00e3o faltam luz nem calefa\u00e7\u00e3o. Ele afirma que a Quaresma j\u00e1 come\u00e7ou na Ucr\u00e2nia, mas para o brasileiro, se trata de um \u201cmomento de gra\u00e7a\u201d:<\/p>\n\n\n\n<p><em>\u201cEu estou vivendo num contexto que \u00e9 uma gra\u00e7a, uma gra\u00e7a de Deus. Que n\u00e3o sou digno de viver nada disso, porque sou realmente fraco, sou covarde, sou um pecador muito grande, mas o que estou vivendo vai al\u00e9m, porque Deus me d\u00e1 a gra\u00e7a de estar contente no meio de toda essa bagun\u00e7a.\u201d<\/em><\/p>\n\n\n\n<p>\u201cD\u00e1 para ver a m\u00e3o de Deus muito forte aqui. Estou vivendo a gratuidade, a gra\u00e7a do amor de Deus. De poder estar aqui no meio desta situa\u00e7\u00e3o toda e poder experimentar o amor de Deus, que Ele \u00e9 bom, que Ele \u00e9 amoroso.\u201d<\/p>\n\n\n\n<div style=\"height:44px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>I Domingo da Quaresma\u00a0\u2013\u00a0Ano C Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto Neste I Domingo da Quaresma a liturgia apresenta-nos Jesus no deserto a ser tentado pelo diabo. Depois de Jesus estar quarenta dias no deserto sentiu fome, &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2022\/03\/06\/novos-ventos-06-de-marco\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[32,8],"tags":[34,33],"class_list":["post-1426","post","type-post","status-publish","format-standard","hentry","category-novos-ventos","category-oracao","tag-boletim","tag-novos-ventos"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=1426"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1426\/revisions"}],"predecessor-version":[{"id":1430,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1426\/revisions\/1430"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=1426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=1426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=1426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}