{"id":1417,"date":"2022-02-27T10:18:20","date_gmt":"2022-02-27T10:18:20","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=1417"},"modified":"2022-02-27T10:18:26","modified_gmt":"2022-02-27T10:18:26","slug":"27-de-fevereiro-a-06-de-marco","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2022\/02\/27\/27-de-fevereiro-a-06-de-marco\/","title":{"rendered":"27 de Fevereiro a 06 de Mar\u00e7o"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Informa\u00e7\u00f5es<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Na Segunda-feira, <\/strong>dia<strong> (28\/02) haver\u00e1:<\/strong><ul><li>Eucaristia na Igreja Matriz, \u00e0s 19:00;<\/li><\/ul><ul><li>Reuni\u00e3o de Comiss\u00f5es de Festas de Nossa Senhora do Bom Sucesso, Nossa Senhora da Paz, Festa do Pescador, \u00e0s 21:00;<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Na Quarta-feira de Cinzas, <\/strong>dia<strong> (02\/03) haver\u00e1:<\/strong><ul><li>Eucaristia nas Quintas do Norte com a imposi\u00e7\u00e3o das Cinzas, \u00e0s 8:00;<\/li><\/ul><ul><li>Eucaristia na Igreja da Torreira com a imposi\u00e7\u00e3o das Cinzas, \u00e0s 19:00;<\/li><\/ul><ul><li>Reuni\u00e3o de Catequistas em S\u00e3o Jacinto a fim de preparar a caminhada quaresmal, \u00e0s 21:30;<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Na Sexta-feira, <\/strong>dia<strong> (04\/03) haver\u00e1:<\/strong><ul><li>Atendimento Paroquial, das 16:00 at\u00e9 \u00e0s 18:00;<\/li><\/ul><ul><li>Adora\u00e7\u00e3o ao Sant\u00edssimo Sacramento, \u00e0s 18:15;<\/li><\/ul><ul><li>Eucaristia na Igreja da Torreira, \u00e0s 19:00;<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>No S\u00e1bado, <\/strong>dia<strong> (05\/03) haver\u00e1:<\/strong><ul><li>Recita\u00e7\u00e3o do Ter\u00e7o Devo\u00e7\u00e3o dos 1\u00ba S\u00e1bados, \u00e0s 16:00;<\/li><\/ul><ul><li>Eucaristia na Igreja da Torreira, \u00e0s 17:00;<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>No Domingo, <\/strong>dia<strong> (06\/03) haver\u00e1:<\/strong><ul><li>Eucaristia nas Quintas do Norte, \u00e0s 8:00;<\/li><\/ul><ul><li>Eucaristia na Igreja da Torreira, \u00e0s 11:00;<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>Na pr\u00f3xima Quarta-feira damos in\u00edcio \u00e0 Quaresma o Papa Francisco prop\u00f4s a toda a Igreja que esse dia de Quarta-feira de cinzas seja um dia de Jejum e Ora\u00e7\u00e3o pela Paz entre a R\u00fassia e a Ucr\u00e2nia.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>A receita da venda dos bolos do 1\u00baAno A de Catequese no S\u00e1bado foi de 74\u20ac e no domingo o valor foi de 101,60\u20ac. Obrigado a todos os que t\u00eam colaborado nestas angaria\u00e7\u00f5es de fundos para as Obras.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>Informa-se que os recibos do grupo dos benfeitores e do Contributo Paroquial para dedu\u00e7\u00e3o do IRS, podem ser levantados na sacristia no final das eucaristias.<\/li><\/ul>\n\n\n\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"intencoes-de-missa\">Inten\u00e7\u00f5es de Missa<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"segunda-feira-21-igreja-matriz-19-00h\"><strong>Segunda-feira, 28 \u2013\u00a0Igreja Matriz, 19:00h<\/strong><\/h3>\n\n\n\n<p><strong>A\u00e7\u00e3o de gra\u00e7as a Nossa Senhora pela vida e sa\u00fade de Maria da Gl\u00f3ria Sim\u00f5es e Fernanda Augusta Fernandes.<\/strong><br><strong>+ Alda de Pinho Nunes Bastos, pais e irm\u00e3os.<\/strong><br><strong>+ Jos\u00e9 de Oliveira Soares e Alzira Mendes de Oliveira.<\/strong><br><strong>+ Domingos Rebelo, esposa e netos.<\/strong><br><strong>+ Anivers\u00e1rio de falecimento de Ant\u00f3nio Lu\u00eds Lopes.<\/strong><br><strong>+ Joaquim Augusto Pinho Silva.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"sexta-feira-25-igreja-matriz-19-00h\"><strong>Sexta-feira, 25 \u2013&nbsp;&nbsp;Igreja Matriz, 19:00h<\/strong><\/h3>\n\n\n\n<p><strong>+ Anivers\u00e1rio Natal\u00edcio de Vivelinda Gareta.<\/strong><br><strong>+ Augusto de Oliveira Fonseca.<\/strong><br><strong>+ Carlos Ant\u00f3nio da Silva Santos e fam\u00edlia.<\/strong><br><strong>+ Pelas Almas do Purgat\u00f3rio.<\/strong><\/p>\n\n\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informa\u00e7\u00f5es Na Segunda-feira, dia (28\/02) haver\u00e1: Eucaristia na Igreja Matriz, \u00e0s 19:00; Reuni\u00e3o de Comiss\u00f5es de Festas de Nossa Senhora do Bom Sucesso, Nossa Senhora da Paz, Festa do Pescador, \u00e0s 21:00; Na Quarta-feira de Cinzas, dia (02\/03) haver\u00e1: Eucaristia &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2022\/02\/27\/27-de-fevereiro-a-06-de-marco\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[9,31],"tags":[30],"class_list":["post-1417","post","type-post","status-publish","format-standard","hentry","category-informacao","category-intencoes","tag-informacao-semanal"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=1417"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1417\/revisions"}],"predecessor-version":[{"id":1418,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1417\/revisions\/1418"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=1417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=1417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=1417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}