{"id":1411,"date":"2022-02-20T10:16:15","date_gmt":"2022-02-20T10:16:15","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=1411"},"modified":"2022-02-20T10:16:19","modified_gmt":"2022-02-20T10:16:19","slug":"novos-ventos-20-de-fevereiro","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2022\/02\/20\/novos-ventos-20-de-fevereiro\/","title":{"rendered":"Novos Ventos &#8211; 20 de Fevereiro"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"vii-domingo-do-tempo-comum-ano-c\"><strong>VII Domingo do Tempo Comum<\/strong>\u00a0\u2013\u00a0<strong>Ano C<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mensagem-dominical-das-paroquias-de-torreira-e-sao-jacinto\"><strong>Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto<\/strong><\/h2>\n\n\n\n<p>A liturgia deste VII domingo do Tempo Comum real\u00e7a atitude de \u201cperd\u00e3o\u201d que devemos usar com os outros. Com bastante frequ\u00eancia somos muito audazes em fazer ju\u00edzos precipitados dos outros, olhamos mais facilmente atrav\u00e9s de sombras, isto \u00e9, uma vis\u00e3o ofuscada do que o outro aparenta ser e n\u00e3o somos capazes de o ver como realmente ele \u00e9. Por isso, \u00e9 necess\u00e1rio ver o outro com \u201colhos novos\u201d, \u00e0 medida do Amor de Jesus Cristo. O evangelho deste domingo revela-nos que devemos usar uma medida diferente com a qual queremos ser medidos. Se amamos aqueles que nos amam que fazemos de extraordin\u00e1rio? Os n\u00e3o crentes tamb\u00e9m amam os amigos. Jesus quer implementar no mundo uma novidade, isto \u00e9, \u00abAmar os inimigos, aqueles que nos fazem mal e levantam cal\u00fanias ou nos injuriam\u00bb. Este \u00e9 um processo que requer de cada um de n\u00f3s uma alquimia, ou seja, ser capaz de ter um olhar diferente sobre os outros, apagando do nosso pensamento as sombras dos relacionamentos que nos retraem e dificultam os verdadeiros relacionamentos e usar um olhar de \u00abMiseric\u00f3rdia segundo o Cora\u00e7\u00e3o de Jesus\u00bb. <strong><\/strong><\/p>\n\n\n\n<p><strong>A leitura do livro de Samuel, <\/strong>&nbsp;apresenta-nos o exemplo concreto de um homem de cora\u00e7\u00e3o magn\u00e2nimo (David) que, tendo a possibilidade de eliminar o seu inimigo, escolhe o perd\u00e3o.<\/p>\n\n\n\n<p><strong>A<\/strong> <strong>Leitura de S\u00e3o Paulo aos Cor\u00edntios, <\/strong>&nbsp;continua a catequese iniciada h\u00e1 uns domingos atr\u00e1s sobre a ressurrei\u00e7\u00e3o. Podemos lig\u00e1-la com o tema central da Palavra de Deus deste domingo \u2013 o amor aos inimigos \u2013 dizendo que \u00e9 na l\u00f3gica do amor que preparamos essa vida plena que Deus nos reserva; e que o amor vivido com radicalidade e sem limita\u00e7\u00f5es \u00e9 um an\u00fancio desse mundo novo que nos espera para al\u00e9m desta terra.<\/p>\n\n\n\n<p><strong>O Evangelho de S\u00e3o Lucas, <\/strong>\u00a0refor\u00e7a esta proposta. Exige dos seguidores de Jesus um cora\u00e7\u00e3o sempre dispon\u00edvel para perdoar, para acolher, para dar a m\u00e3o, independentemente de quem esteja do outro lado. N\u00e3o se trata de amar apenas os membros do pr\u00f3prio grupo social, da pr\u00f3pria ra\u00e7a, do pr\u00f3prio povo, da pr\u00f3pria classe, partido, igreja ou clube de futebol; trata-se de um amor sem discrimina\u00e7\u00f5es, que nos leve a ver em cada homem \u2013 mesmo no inimigo \u2013 um nosso irm\u00e3o.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"evangelho-de-nosso-senhor-jesus-cristo-segundo-sao-lucas\"><strong><u>Evangelho de Nosso Senhor Jesus Cristo Segundo S\u00e3o Lucas<\/u><\/strong><\/h3>\n\n\n\n<p>Naquele tempo, Jesus falou aos seus disc\u00edpulos, dizendo: \u00abDigo-vos a v\u00f3s que Me escutais: Amai os vossos inimigos, fazei bem aos que vos odeiam; aben\u00e7oai os que vos amaldi\u00e7oam, orai por aqueles que vos injuriam. A quem te bater numa face, apresenta-lhe tamb\u00e9m a outra; e a quem te levar a capa, deixa-lhe tamb\u00e9m a t\u00fanica. D\u00e1 a todo aquele que te pedir e ao que levar o que \u00e9 teu, n\u00e3o o reclames. Como quereis que os outros vos fa\u00e7am, fazei-lho v\u00f3s tamb\u00e9m. Se amais aqueles que vos amam, que agradecimento mereceis? Tamb\u00e9m os pecadores amam aqueles que os amam. Se fazeis bem aos que vos fazem bem, que agradecimento mereceis? Tamb\u00e9m os pecadores fazem o mesmo. E se emprestais \u00e0queles de quem esperais receber, que agradecimento mereceis? Tamb\u00e9m os pecadores emprestam aos pecadores, a fim de receberem outro tanto. V\u00f3s, por\u00e9m, amai os vossos inimigos, fazei o bem e emprestai, sem nada esperar em troca. Ent\u00e3o ser\u00e1 grande a vossa recompensa e sereis filhos do Alt\u00edssimo, que \u00e9 bom at\u00e9 para os ingratos e os maus. Sede misericordiosos, como o vosso Pai \u00e9 misericordioso. N\u00e3o julgueis e n\u00e3o sereis julgados. N\u00e3o condeneis e n\u00e3o sereis condenados. Perdoai e sereis perdoados. Dai e dar-se-vos-\u00e1: deitar-vos-\u00e3o no rega\u00e7o uma boa medida, calcada, sacudida, a transbordar. A medida que usardes com os outros ser\u00e1 usada tamb\u00e9m convosco\u00bb.<\/p>\n\n\n\n<p><strong>Palavra do Senhor<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<p><strong><u>&nbsp;Palavra de Vida \u2013 Fevereiro<\/u><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"aqueles-que-vem-a-mim-nao-os-rejeitarei-jo-6-37\"><strong>\u00ab\u00c0queles que v\u00eam a Mim, n\u00e3o os rejeitarei\u00bb.&nbsp;<\/strong><em>(Jo 6,37)<\/em><\/h3>\n\n\n\n<p>No Qu\u00e9bec (Canad\u00e1), uma comunidade crist\u00e3 que vive a Palavra dedica-se a apoiar muitas das fam\u00edlias que chegam ao seu pa\u00eds, de variadas proveni\u00eancias: Fran\u00e7a, Egito, S\u00edria, L\u00edbano, Congo\u2026 todos s\u00e3o acolhidos e ajudados, tamb\u00e9m no esfor\u00e7o de inser\u00e7\u00e3o. Isso significa responder \u00e0s suas m\u00faltiplas necessidades: preencher os formul\u00e1rios relativos ao estatuto de refugiado ou residente, fazer a liga\u00e7\u00e3o com a escola dos filhos, acompanh\u00e1-los a descobrir o seu bairro. \u00c9 tamb\u00e9m importante a inscri\u00e7\u00e3o em cursos de franc\u00eas e a procura de trabalho.<\/p>\n\n\n\n<p>Guy e Micheline escrevem: \u00abUma fam\u00edlia da S\u00edria que, fugindo da guerra, tinha vindo para o Canad\u00e1, encontrou outra fam\u00edlia que tinha acabado de chegar e ainda se encontrava muito desorientada. Atrav\u00e9s das redes sociais, ativou a rede de solidariedade e muitos amigos conseguiram arranjar o que era necess\u00e1rio: camas, sof\u00e1s, mesas, cadeiras, utens\u00edlios de cozinha, vestu\u00e1rio. Livros e jogos para as crian\u00e7as foram espontaneamente oferecidos por algumas crian\u00e7as das nossas fam\u00edlias, sensibilizadas pelos pais. Tendo recebido mais do que precisavam, ajudaram tamb\u00e9m outras fam\u00edlias pobres do seu pr\u00e9dio. A Palavra de vida daquele m\u00eas tinha sido muito apropriada: \u201cAmar\u00e1s o teu pr\u00f3ximo como a ti mesmo!\u201d\u00bb.<\/p>\n\n\n\n<p><em>Letizia Magri<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/26.png\" alt=\"\" class=\"wp-image-1412\" width=\"495\" height=\"647\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/26.png 500w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/26-229x300.png 229w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"ucrania-bispos-italianos-nao-ha-mais-lugar-para-as-armas-na-historia-da-humanidade\">Ucr\u00e2nia. Bispos italianos: &#8220;n\u00e3o h\u00e1 mais lugar para as armas na hist\u00f3ria da humanidade!&#8221;<\/h3>\n\n\n\n<p id=\"o-que-esta-acontecendo-na-fronteira-entre-ucrania-e-russia-le-se-no-apelo-preocupa-o-mundo-inteiro-o-risco-concreto-de-uma-guerra-ou-ate-mesmo-a-hipotese-de-que-um-conflito-possa-ser-desencadeado-perturba-a-alma-abala-as-consciencias-aumenta-as-muitas-preocupacoes-que-a-humanidade-ja-esta-vivendo-por-causa-da-pandemia-e-outras-pandemias-que-estao-atravessando-o-planeta-pobreza-doencas-ausencia-de-educacao-conflitos-locais-e-regionais\">&#8220;O que est\u00e1 acontecendo na fronteira entre Ucr\u00e2nia e R\u00fassia \u2013 l\u00ea-se no apelo &#8211; preocupa o mundo inteiro. O risco concreto de uma guerra &#8211; ou at\u00e9 mesmo a hip\u00f3tese de que um conflito possa ser desencadeado &#8211; perturba a alma, abala as consci\u00eancias, aumenta as muitas preocupa\u00e7\u00f5es que a humanidade j\u00e1 est\u00e1 vivendo por causa da pandemia e outras \u2018pandemias\u2019 que est\u00e3o atravessando o planeta: pobreza, doen\u00e7as, aus\u00eancia de educa\u00e7\u00e3o, conflitos locais e regionais.&#8221;<\/p>\n\n\n\n<p><strong>Por uma coexist\u00eancia respeitosa e de coopera\u00e7\u00e3o na Europa<\/strong><\/p>\n\n\n\n<p>&#8220;No dia em que recordamos os Santos Cirilo e Met\u00f3dio, co-patronos da Europa (celebrados em 14 de fevereiro), escrevem os bispos italianos, apelamos \u00e0s nossas ra\u00edzes comuns na f\u00e9 crist\u00e3, que \u00e9 uma mensagem de paz, para que no Velho Continente haja sempre uma coexist\u00eancia respeitosa, colabora\u00e7\u00e3o no n\u00edvel econ\u00f4mico, respeito e di\u00e1logo duradouros.&#8221;<\/p>\n\n\n\n<p><strong>Jamais desistir da paz<\/strong><\/p>\n\n\n\n<p>&#8220;A paz \u00e9 um bem precioso do qual a humanidade n\u00e3o pode e nunca deve desistir. Invocamos nosso Senhor Jesus Cristo, Pr\u00edncipe da Paz, e a Sant\u00edssima Virgem, particularmente venerada na Ucr\u00e2nia na Bas\u00edlica da M\u00e3e de Deus de Zarvanytsia, para que um terr\u00edvel flagelo possa ser poupado. Convidamos todas as Igrejas da It\u00e1lia a unirem-se a esta inten\u00e7\u00e3o de ora\u00e7\u00e3o&#8221;, exortam por fim os bispos.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1000\" height=\"563\" data-id=\"1414\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/27.jpg\" alt=\"\" class=\"wp-image-1414\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/27.jpg 1000w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/27-300x169.jpg 300w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/27-768x432.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"750\" height=\"422\" data-id=\"1413\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/28.jpg\" alt=\"\" class=\"wp-image-1413\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/28.jpg 750w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/28-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"igreja-da-polonia-faz-apelo-aos-bispos-da-russia-e-ucrania\">Igreja da Pol\u00f4nia faz apelo aos bispos da R\u00fassia e Ucr\u00e2nia<\/h3>\n\n\n\n<p><strong>Um grito para prevenir a morte e sofrimento<\/strong><\/p>\n\n\n\n<p>Na carta G\u0105decki apresentou-se como irm\u00e3o e pastor de um &#8220;pa\u00eds adjacente&#8221;, ligado \u00e0s terras russas e ucranianas &#8220;por uma hist\u00f3ria comum e pela santa f\u00e9 crist\u00e3&#8221;. Referindo-se \u00e0s not\u00edcias da m\u00eddia sobre um s\u00e9rio risco armado no pa\u00eds, escreve: &#8220;Que as nossas ora\u00e7\u00f5es sejam um grito para evitar o sofrimento e a morte de milhares de seres humanos inocentes, especialmente os mais fracos e indefesos, que n\u00e3o ter\u00e3o a for\u00e7a ou a oportunidade de escapar quando explodir a guerra&#8221;. &#8220;Toda guerra \u00e9 uma trag\u00e9dia da humanidade&#8221; que destr\u00f3i a vida de milhares de pessoas, de ambos os lados, e de suas fam\u00edlias, salientou o presidente do Episcopado polon\u00eas: &#8220;Muitos de ambos os lados ficam mutilados, e milhares de outros carregam feridas internas que s\u00e3o dif\u00edceis de cicatrizar&#8221;.<\/p>\n\n\n\n<p><strong>Amizade e respeito rec\u00edproco<\/strong><\/p>\n\n\n\n<p>A natureza dram\u00e1tica da guerra entre a R\u00fassia e a Ucr\u00e2nia \u00e9 agravada pelo fato de serem ambos povos crist\u00e3os e eslavos: &#8220;Do ponto de vista humano e do ponto de vista do julgamento divino, estes dois povos deveriam ter muito em comum e deixar de lado o \u00f3dio, dando lugar ao respeito rec\u00edproco e \u00e0 amizade. Por\u00e9m, uma condi\u00e7\u00e3o indispens\u00e1vel \u00e9 o respeito pelos direitos dos povos, incluindo o direito \u00e0 autodetermina\u00e7\u00e3o e \u00e0 integridade territorial&#8221;, afirma G\u0105decki. Ao recordar as duas grandes guerras ocorridas no s\u00e9culo passado, o arcebispo polon\u00eas lembrou das palavras de S\u00e3o Jo\u00e3o Paulo II em sua\u00a0<em>Mensagem para o Dia Mundial da Paz<\/em>\u00a0em 2000: &#8220;As guerras s\u00e3o frequentemente causa de outras guerras, porque alimentam \u00f3dios profundos, criam situa\u00e7\u00f5es de injusti\u00e7a e espezinham a dignidade e os direitos das pessoas.<\/p>\n\n\n\n<div style=\"height:43px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>VII Domingo do Tempo Comum\u00a0\u2013\u00a0Ano C Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto A liturgia deste VII domingo do Tempo Comum real\u00e7a atitude de \u201cperd\u00e3o\u201d que devemos usar com os outros. Com bastante frequ\u00eancia somos muito audazes em &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2022\/02\/20\/novos-ventos-20-de-fevereiro\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[32,8],"tags":[34,33],"class_list":["post-1411","post","type-post","status-publish","format-standard","hentry","category-novos-ventos","category-oracao","tag-boletim","tag-novos-ventos"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=1411"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1411\/revisions"}],"predecessor-version":[{"id":1415,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1411\/revisions\/1415"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=1411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=1411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=1411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}