{"id":1404,"date":"2022-02-13T09:37:05","date_gmt":"2022-02-13T09:37:05","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=1404"},"modified":"2022-02-13T09:37:11","modified_gmt":"2022-02-13T09:37:11","slug":"novos-ventos-13-de-fevereiro","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2022\/02\/13\/novos-ventos-13-de-fevereiro\/","title":{"rendered":"Novos Ventos &#8211; 13 de Fevereiro"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\" id=\"vi-domingo-do-tempo-comum-ano-c\"><strong>VI Domingo do Tempo Comum<\/strong>\u00a0\u2013\u00a0<strong>Ano C<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"mensagem-dominical-das-paroquias-de-torreira-e-sao-jacinto\"><strong>Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto<\/strong><\/h2>\n\n\n\n<p>A liturgia do VI domingo do Tempo Comum coloca em evid\u00eancia uma proposta de Beatitude ou felicidade que n\u00e3o consiste na opul\u00eancia ou riqueza neste mundo, mas ser rico aos olhos de Deus. A primeira Bem-Aventuran\u00e7a que nos \u00e9 proposta consiste na pobreza, isto \u00e9, n\u00e3o estarmos apegados aos bens materiais porque seremos compensados por outra riqueza que n\u00e3o nos ser\u00e1 tirada \u00ab\u00e9 vosso o reino dos c\u00e9us\u00bb. Os pobres e humildes s\u00e3o aqueles que se deixam seduzir e guiar por Jesus Cristo. Maria no Magnificat diz \u00abporque olhou para a humildade da sua serva\u00bb. As Bem-Aventuran\u00e7as s\u00e3o para n\u00f3s uma proposta de felicidade, mas que se obt\u00e9m atrav\u00e9s do servi\u00e7o a Deus e aos outros e essa consola\u00e7\u00e3o nos \u00e9 garantida por Deus. <strong><\/strong><\/p>\n\n\n\n<p><strong>A leitura do livro de Jeremias, <\/strong>&nbsp;p\u00f5e frente a frente a autossufici\u00eancia daqueles que prescindem de Deus e escolhem viver \u00e0 margem das suas propostas, com a atitude dos que escolhem confiar em Deus e entregar-se nas suas m\u00e3os. O profeta Jeremias avisa que prescindir de Deus \u00e9 percorrer um caminho de morte e renunciar \u00e0 felicidade e \u00e0 vida plenas.<\/p>\n\n\n\n<p><strong>A<\/strong> <strong>Leitura de S\u00e3o Paulo aos Cor\u00edntios, <\/strong>&nbsp;falando da nossa ressurrei\u00e7\u00e3o \u2013 consequ\u00eancia da ressurrei\u00e7\u00e3o de Cristo \u2013, sugere que a nossa vida n\u00e3o pode ser lida exclusivamente \u00e0 luz dos crit\u00e9rios deste mundo: ela atinge o seu sentido pleno e total quando, pela ressurrei\u00e7\u00e3o, desabrocharmos para o Homem Novo. Ora, isso s\u00f3 acontecer\u00e1 se n\u00e3o nos conformarmos com a l\u00f3gica deste mundo, mas apontarmos a nossa exist\u00eancia para Deus e para a vida plena que Ele tem para n\u00f3s.<\/p>\n\n\n\n<p><strong>O Evangelho de S\u00e3o Lucas, <\/strong>\u00a0proclama \u201cfelizes\u201d esses que constroem a sua vida \u00e0 luz dos valores propostos por Deus e infelizes os que preferem o ego\u00edsmo, o orgulho e a autossufici\u00eancia. Sugere que os preferidos de Deus s\u00e3o os que vivem na simplicidade, na humildade e na debilidade, mesmo que, \u00e0 luz dos crit\u00e9rios do mundo, eles sejam desgra\u00e7ados, marginais, incapazes de fazer ouvir a sua voz diante do trono dos poderosos que presidem aos destinos do mundo.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"evangelho-de-nosso-senhor-jesus-cristo-segundo-sao-lucas\"><strong><u>Evangelho de Nosso Senhor Jesus Cristo Segundo S\u00e3o Lucas<\/u><\/strong><\/h3>\n\n\n\n<p>Naquele tempo, Jesus desceu do monte, na companhia dos Ap\u00f3stolos, e deteve-Se num s\u00edtio plano, com numerosos disc\u00edpulos e uma grande multid\u00e3o<br>de toda a Judeia, de Jerusal\u00e9m e do litoral de Tiro e Sid\u00f3nia.<br>Erguendo ent\u00e3o os olhos para os disc\u00edpulos, disse:<br>Bem-aventurados v\u00f3s, os pobres, porque \u00e9 vosso o reino de Deus.<br>Bem-aventurados v\u00f3s, que agora tendes fome, porque sereis saciados.<br>Bem-aventurados v\u00f3s, que agora chorais, porque haveis de rir.<br>Bem-aventurados sereis, quando os homens vos odiarem, quando vos rejeitarem e insultarem e prescreverem o vosso nome como infame, por causa do Filho do homem. Alegrai-vos e exultai nesse dia, porque \u00e9 grande no C\u00e9u a vossa recompensa. Era assim que os seus antepassados tratavam os profetas. Mas ai de v\u00f3s, os ricos, porque j\u00e1 recebestes a vossa consola\u00e7\u00e3o.<br>Ai de v\u00f3s, que agora estais saciados, porque haveis de ter fome. Ai de v\u00f3s, que rides agora, porque haveis de entristecer-vos e chorar. Ai de v\u00f3s, quando todos os homens vos elogiarem. Era assim que os seus antepassados<br>tratavam os falsos profetas.<\/p>\n\n\n\n<p><strong>Palavra do Senhor<\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<p><strong><u>&nbsp;Palavra de Vida \u2013 Fevereiro<\/u><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"aqueles-que-vem-a-mim-nao-os-rejeitarei-jo-6-37\"><strong>\u00ab\u00c0queles que v\u00eam a Mim, n\u00e3o os rejeitarei\u00bb.&nbsp;<\/strong><em>(Jo 6,37)<\/em><\/h3>\n\n\n\n<p>\u00c9 mesmo uma boa not\u00edcia: Deus ama a todos imensamente, a sua ternura e a sua miseric\u00f3rdia s\u00e3o dirigidas a cada homem e a cada mulher. Ele \u00e9 o Pai paciente e misericordioso que espera por todos aqueles que, movidos pela voz interior, se p\u00f5em a caminho.<\/p>\n\n\n\n<p>Muitas vezes, n\u00f3s sofremos de desconfian\u00e7a: por que raz\u00e3o \u00e9 que Jesus me haveria de acolher? O que \u00e9 que Ele querer\u00e1 de mim? Na realidade, Jesus pede-nos apenas que nos deixemos atrair por Ele, libertando o nosso cora\u00e7\u00e3o de tudo aquilo que nos perturba, para, com confian\u00e7a, aceitarmos o Seu amor gratuito.<\/p>\n\n\n\n<p>Mas \u00e9 um convite que requer tamb\u00e9m a nossa responsabilidade. De facto, se experimentarmos uma tal abund\u00e2ncia de ternura por parte de Jesus, sentir-nos-emos tamb\u00e9m impelidos a acolh\u00ea-Lo em cada pr\u00f3ximo<sup>[2]<\/sup>: homem ou mulher, jovem ou idoso, saud\u00e1vel ou doente, da nossa cultura ou n\u00e3o\u2026 e n\u00e3o rejeitaremos ningu\u00e9m.<\/p>\n\n\n\n<p><em>Letizia Magri<\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/22.jpg\" alt=\"\" class=\"wp-image-1405\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/22.jpg 720w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/22-300x300.jpg 300w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/22-150x150.jpg 150w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"o-papa-pensar-na-morte-nos-ajuda-a-olhar-a-vida-com-novos-olhos\"><strong><u>O Papa: pensar na morte nos ajuda a olhar a vida com novos olhos<\/u><\/strong><\/h3>\n\n\n\n<p>&#8220;\u00c9 apenas atrav\u00e9s da f\u00e9 na ressurrei\u00e7\u00e3o que podemos olhar para o abismo da morte sem nos deixarmos dominar pelo medo. N\u00e3o s\u00f3: mas tamb\u00e9m podemos atribuir \u00e0 morte um papel positivo&#8221;, disse Francisco na Audi\u00eancia Geral desta quarta-feira.<\/p>\n\n\n\n<p><strong>A pandemia de coronav\u00edrus colocou a morte em evid\u00eancia<\/strong><\/p>\n\n\n\n<p><em>Amados irm\u00e3os e irm\u00e3s, talvez algumas pessoas pensem que esta linguagem e este tema sejam apenas uma heran\u00e7a do passado, mas na realidade a nossa rela\u00e7\u00e3o com a morte nunca se relaciona com o passado, mas sempre com o presente. O Papa em\u00e9rito Bento XVI disse nesses dias atr\u00e1s, falando de si mesmo, que ele est\u00e1 diante da porta sombria da morte. \u00c9 bonito agradecer ao Papa por ter essa lucidez aos 95 anos de dizer que est\u00e1 diante da porta sombria da morte. Um bom conselho ele nos d\u00e1! A chamada cultura do \u201cbem-estar\u201d procura remover a realidade da morte, mas de uma forma dram\u00e1tica a pandemia do coronav\u00edrus voltou a coloc\u00e1-la em evid\u00eancia. Foi triste, morte por todo lado. Muitos irm\u00e3os e irm\u00e3s perderam entes queridos sem poderem estar ao lado deles, e isto tornou a morte ainda mais dif\u00edcil de aceitar e de elaborar. <\/em>Segundo Francisco, &#8220;procuramos de todas as maneiras banir o pensamento da nossa finitude, iludindo-nos em pensar que podemos retirar o poder da morte e afastar o temor. A f\u00e9 crist\u00e3 n\u00e3o \u00e9 uma forma de exorcizar o medo da morte, pelo contr\u00e1rio, nos ajuda a enfrent\u00e1-la. Antes ou depois todos n\u00f3s passaremos por aquela porta&#8221;.<\/p>\n\n\n\n<p><strong>O sud\u00e1rio n\u00e3o tem bolso<\/strong><\/p>\n\n\n\n<p>A seguir, o Papa disse que &#8220;verdadeira luz que ilumina o mist\u00e9rio da morte prov\u00e9m da ressurrei\u00e7\u00e3o de Cristo. Existe uma certeza, Cristo ressuscitou, Cristo est\u00e1 vivo entre n\u00f3s e esta luz nos espera atr\u00e1s daquela porta sombria da morte&#8221;.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"750\" height=\"422\" data-id=\"1406\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/23.jpg\" alt=\"\" class=\"wp-image-1406\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/23.jpg 750w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/23-300x169.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"1407\" src=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/24-1024x576.jpg\" alt=\"\" class=\"wp-image-1407\" srcset=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/24-1024x576.jpg 1024w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/24-300x169.jpg 300w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/24-768x432.jpg 768w, https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-content\/uploads\/2022\/02\/24.jpg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"crise-na-ucrania-francisco-a-guerra-e-uma-loucura\"><strong><u>Crise na Ucr\u00e2nia, Francisco: a guerra \u00e9 uma loucura<\/u><\/strong><\/h3>\n\n\n\n<p>Ap\u00f3s a catequese na audi\u00eancia geral, o Papa agradeceu a todas as pessoas que rezaram pela paz no pa\u00eds da Europa Oriental em 26 de janeiro e pediu-lhes que continuem a implorar a Deus para que prevale\u00e7a um &#8220;di\u00e1logo s\u00e9rio&#8221;.<\/p>\n\n\n\n<p><strong>A Ora\u00e7\u00e3o em 26 de janeiro<\/strong><\/p>\n\n\n\n<p>Em 26 de janeiro passado, no dia dedicado por Francisco ao recolhimento pela crise que vive a na\u00e7\u00e3o do leste europeu, o Papa havia conclu\u00eddo a audi\u00eancia geral com esta inten\u00e7\u00e3o: &#8220;Pe\u00e7amos insistentemente ao Senhor que aquela terra possa ver florescer a fraternidade e superar feridas, medos e divis\u00f5es&#8221;. Recordando ent\u00e3o os sofrimentos do povo ucraniano ligados \u00e0 Segunda Guerra Mundial, o Pont\u00edfice lembrou que mais de cinco milh\u00f5es de pessoas foram aniquiladas durante a guerra: &#8220;\u00c9 um povo sofredor que merece a paz&#8221;.<\/p>\n\n\n\n<p><strong>Diplomacia ao trabalho<\/strong><\/p>\n\n\n\n<p>As esperan\u00e7as de paz tamb\u00e9m est\u00e3o ligadas aos esfor\u00e7os diplom\u00e1ticos para encontrar uma solu\u00e7\u00e3o para a crise na Ucr\u00e2nia. Ap\u00f3s conversas com o presidente russo Putin em Moscou na segunda-feira, o presidente franc\u00eas Macron teve um encontro face a face com o chefe de Estado ucraniano Zelensky em Kiev nesta ter\u00e7a-feira. Falando aos jornalistas, o chefe do Eliseu disse que agora existem &#8220;solu\u00e7\u00f5es concretas pr\u00e1ticas&#8221;. &#8220;Agora&#8221;, disse ele, &#8220;h\u00e1 a possibilidade de fazer avan\u00e7ar as negocia\u00e7\u00f5es&#8221; sobre a paz.<\/p>\n\n\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>VI Domingo do Tempo Comum\u00a0\u2013\u00a0Ano C Mensagem dominical das par\u00f3quias de Torreira e S\u00e3o Jacinto A liturgia do VI domingo do Tempo Comum coloca em evid\u00eancia uma proposta de Beatitude ou felicidade que n\u00e3o consiste na opul\u00eancia ou riqueza neste &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2022\/02\/13\/novos-ventos-13-de-fevereiro\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[32,8],"tags":[34,33],"class_list":["post-1404","post","type-post","status-publish","format-standard","hentry","category-novos-ventos","category-oracao","tag-boletim","tag-novos-ventos"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=1404"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1404\/revisions"}],"predecessor-version":[{"id":1408,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1404\/revisions\/1408"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=1404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=1404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=1404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}