{"id":1259,"date":"2021-10-10T09:07:56","date_gmt":"2021-10-10T09:07:56","guid":{"rendered":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/?p=1259"},"modified":"2021-10-10T09:08:01","modified_gmt":"2021-10-10T09:08:01","slug":"10-a-17-de-outubro","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2021\/10\/10\/10-a-17-de-outubro\/","title":{"rendered":"10 a 17 de Outubro"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Informa\u00e7\u00f5es<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Na Quarta-feira, <\/strong>dia<strong> (13\/10) haver\u00e1:<\/strong><ul><li>Eucaristia nas Quintas do Norte, \u00e0s 20:00;<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Na Sexta-feira, <\/strong>dia<strong> (15\/10) haver\u00e1:<\/strong><ul><li>Atendimento Paroquial, das 16:00 at\u00e9 \u00e0s 18:30;<\/li><\/ul><ul><li>Eucaristia na Igreja Matriz, \u00e0s 19:00;<\/li><\/ul><ul><li>Reuni\u00e3o do Conselho Econ\u00f3mico, \u00e0s 21:00;<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>No S\u00e1bado, <\/strong>dia<strong> (16\/10) haver\u00e1:<\/strong><ul><li>Eucaristia na Igreja Matriz, \u00e0s 17:00;<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>No Domingo, <\/strong>dia<strong> (17\/10) haver\u00e1:<\/strong><ul><li>Eucaristia nas Quintas do Norte, \u00e0s 8:00;<\/li><\/ul><ul><li>Eucaristia na Igreja da Torreira, \u00e0s 11:00;<\/li><\/ul><\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>A receita da venda dos bolos no fim-de-semana na Igreja Paroquial no s\u00e1bado foi de 112.20\u20ac e no domingo 71.50\u20ac. Obrigado a todos os que t\u00eam colaborado nestas angaria\u00e7\u00f5es de fundos para as Obras.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>Informamos, que a partir deste m\u00eas o grupo dos benfeitores poder\u00e1 realizar o pagamento da sua quota: esta poder\u00e1 ser mensal, trimestral, semestral ou anualmente, conforme deseja o benfeitor.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>Durante o m\u00eas de outubro far-se-\u00e1 a recita\u00e7\u00e3o do Ros\u00e1rio na Igreja Matriz de segunda a sexta-feira, \u00e0s 18:30 e aos s\u00e1bados e domingos, \u00e0s 16:00.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<ul class=\"wp-block-list\"><li>Durante os meses de Outubro, Novembro e Dezembro far-se-\u00e1 o contributo Paroquial. O contributo paroquial, outrora chamado c\u00f4ngrua, \u00e9 assim a contribui\u00e7\u00e3o regular dos paroquianos para as despesas da sua Par\u00f3quia que se prendem com o culto divino, as obras apost\u00f3licas e de caridade, a sustenta\u00e7\u00e3o dos seus ministros, os sal\u00e1rios e encargos dos funcion\u00e1rios, os custos de manuten\u00e7\u00e3o (\u00e1gua, electricidade, telefone\u2026). Os paroquianos que n\u00e3o fizerem o seu contributo ficam sujeitos \u00e0s taxas dos emolumentos propostos pela diocese.<\/li><\/ul>\n\n\n\n<div style=\"height:46px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Inten\u00e7\u00f5es de Missa<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Quarta-feira, 13 \u2013\u00a0Quintas do Norte, 20:00h<\/strong><\/h3>\n\n\n\n<p><strong>+ 1\u00ba Anivers\u00e1rio de Alzira Mendes de Oliveira.<\/strong><br><strong>+ Manuel Maria Valente.<\/strong><br><strong>+ Ant\u00f3nio Joaquim Rodrigues, Celeste Lamego e Manuel Canas.<\/strong><br><strong>+ Anivers\u00e1rio de falecimento de Maria do Carmo.<\/strong><br><strong>+ Sofia da Silva, Carlos Valente e familiares.<\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sexta-feira, 15 \u2013 Igreja Matriz, 19:00h<\/strong><\/h3>\n\n\n\n<p><strong>+ Carlos de Oliveira e Cunha.<\/strong><br><strong>+ Maria do Nacimento Pinho Silva.<\/strong><br><strong>+ Augusta de Jesus Oliveira Pinho.<\/strong><br><strong>+ Anivers\u00e1rio de Peter Kern.<\/strong><\/p>\n\n\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Informa\u00e7\u00f5es Na Quarta-feira, dia (13\/10) haver\u00e1: Eucaristia nas Quintas do Norte, \u00e0s 20:00; Na Sexta-feira, dia (15\/10) haver\u00e1: Atendimento Paroquial, das 16:00 at\u00e9 \u00e0s 18:30; Eucaristia na Igreja Matriz, \u00e0s 19:00; Reuni\u00e3o do Conselho Econ\u00f3mico, \u00e0s 21:00; No S\u00e1bado, dia &hellip; <a href=\"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/2021\/10\/10\/10-a-17-de-outubro\/\">Continuar a ler <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"categories":[9,31],"tags":[30],"class_list":["post-1259","post","type-post","status-publish","format-standard","hentry","category-informacao","category-intencoes","tag-informacao-semanal"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/comments?post=1259"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1259\/revisions"}],"predecessor-version":[{"id":1260,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/posts\/1259\/revisions\/1260"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/media?parent=1259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/categories?post=1259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/paroquiadatorreira\/wp-json\/wp\/v2\/tags?post=1259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}