{"id":8240,"date":"2020-02-14T11:13:35","date_gmt":"2020-02-14T11:13:35","guid":{"rendered":"http:\/\/diocese-aveiro.pt\/cultura\/?p=8240"},"modified":"2020-02-14T11:14:02","modified_gmt":"2020-02-14T11:14:02","slug":"noticias-eutanasia-juristas-empresarios-enfermeiros-medicos-e-psicologos-afirmam-oposicao-a-morte-a-pedido-e-criticam-a-pressa-parlamentar","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/cultura\/noticias-eutanasia-juristas-empresarios-enfermeiros-medicos-e-psicologos-afirmam-oposicao-a-morte-a-pedido-e-criticam-a-pressa-parlamentar\/","title":{"rendered":"Not\u00edcias | Eutan\u00e1sia: Juristas, empres\u00e1rios, enfermeiros, m\u00e9dicos e psic\u00f3logos afirmam oposi\u00e7\u00e3o \u00e0 \u00abmorte a pedido\u00bb e criticam a \u00abpressa\u00bb parlamentar"},"content":{"rendered":"<p style=\"text-align: right;\">Not\u00edcia e foto recolhidas da <a href=\"https:\/\/agencia.ecclesia.pt\/portal\/eutanasia-juristas-empresarios-enfermeiros-medicos-e-psicologos-afirmam-oposicao-a-morte-a-pedido-e-criticam-a-pressa-parlamentar\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ag\u00eancia Ecclesia<\/a><\/p>\n<p style=\"text-align: justify;\"><em>Comunicado conjunto de cinco associa\u00e7\u00e3o cat\u00f3licas sublinha que legaliza\u00e7\u00e3o a morte a pedido \u00e9 uma \u201cquest\u00e3o de relevante alcance civilizacional\u201d<\/em><\/p>\n<p style=\"text-align: justify;\">Cinco associa\u00e7\u00f5es profissionais cat\u00f3licas divulgaram esta quinta-feira um comunicado onde asseguram que a morte \u201cn\u00e3o \u00e9 resposta\u201d diante do sofrimento, reafirmam a oposi\u00e7\u00e3o \u00e0 morte a pedido e criticam \u201ca pressa\u201d na vota\u00e7\u00e3o da legaliza\u00e7\u00e3o da eutan\u00e1sia.<\/p>\n<p style=\"text-align: justify;\">\u201cA resposta \u00e0 doen\u00e7a e ao sofrimento nunca pode ser a morte provocada. Nunca podemos desistir de combater e aliviar o sofrimento e a eutan\u00e1sia e o suic\u00eddio assistido s\u00e3o uma forma de desistir desse combate: n\u00e3o eliminam ou aliviam o sofrimento, eliminam a vida da pessoa que sofre\u201d, afirma o comunicado.<\/p>\n<p style=\"text-align: justify;\">Num documento assinado pela Associa\u00e7\u00e3o Cat\u00f3lica dos Enfermeiros e Profissionais de Sa\u00fade, Associa\u00e7\u00e3o dos Juristas Cat\u00f3licos, Associa\u00e7\u00e3o dos M\u00e9dicos Cat\u00f3licos Portugueses, Associa\u00e7\u00e3o dos Psic\u00f3logos Cat\u00f3licos e Associa\u00e7\u00e3o Cat\u00f3lica de Empres\u00e1rios e Gestores, refere-se que o \u201ct\u00e3o r\u00e1pido agendamento parlamentar\u201d da vota\u00e7\u00e3o dos projetos de legaliza\u00e7\u00e3o da eutan\u00e1sia revela \u201cdesconsidera\u00e7\u00e3o dos instrumentos da democracia participativa\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cNenhum dos dois maiores partidos com representa\u00e7\u00e3o parlamentar inscreveu nos seus programas eleitorais a legaliza\u00e7\u00e3o da eutan\u00e1sia e do suic\u00eddio assistido. N\u00e3o estamos perante mat\u00e9ria de import\u00e2ncia secund\u00e1ria que dispense uma qualquer forma de manifesta\u00e7\u00e3o da vontade popular\u201d, escrevem as associa\u00e7\u00f5es.<\/p>\n<p style=\"text-align: justify;\">Para as signat\u00e1rias do documento, a proposta de legaliza\u00e7\u00e3o da eutan\u00e1sia \u00e9 uma \u201cquest\u00e3o de relevante alcance civilizacional\u201d porque \u201cquebra\u201d um princ\u00edpio b\u00e1sico e alicerce da ordem jur\u00eddica portuguesa, a que afirma a \u201cproibi\u00e7\u00e3o de matar\u201d e a \u201cinviolabilidade da vida humana\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cDerrubado esse alicerce, todo o edif\u00edcio da civiliza\u00e7\u00e3o e da ordem jur\u00eddica amea\u00e7ar\u00e1 ruir. \u00c9 assim imposs\u00edvel conter a pr\u00e1tica da eutan\u00e1sia e do suic\u00eddio assistido limitando-a a casos excecionais. Isso mesmo demonstra a pr\u00e1tica dos pa\u00edses que seguiram tal via h\u00e1 mais tempo \u2013 Holanda e B\u00e9lgica \u2013 e, mais recentemente \u2013 o Canad\u00e1\u201d, acrescenta o documento.<\/p>\n<p style=\"text-align: justify;\">Para as cinco associa\u00e7\u00f5es cat\u00f3licas, \u201ca vida humana nunca perde dignidade, nunca deixa de ser merecedora de prote\u00e7\u00e3o\u201d porque \u201cn\u00e3o h\u00e1 vidas indignas de ser vividas\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cPara combater e aliviar o sofrimento, servem, antes, os cuidados paliativos, ainda n\u00e3o acess\u00edveis a todos os portugueses. Generalizar esse acesso, acolhendo esse sofrimento, deveria ser a prioridade e a pressa dos que querem votar a legaliza\u00e7\u00e3o da eutan\u00e1sia e do suic\u00eddio assistido\u201d, afirmam.<\/p>\n<p style=\"text-align: justify;\">Os deputados portugueses v\u00e3o discutir e votar a legaliza\u00e7\u00e3o da eutan\u00e1sia de quatro projetos de lei \u2013 apresentados pelo PS, Bloco de Esquerda (BE), PAN e Os Verdes (PEV) \u2013, no pr\u00f3ximo dia 20, na Assembleia da Rep\u00fablica.<\/p>\n<p style=\"text-align: justify;\">Em 2016, a CEP\u00a0<a href=\"https:\/\/agencia.ecclesia.pt\/portal\/eutanasia-o-que-esta-em-causa-contributos-para-um-dialogo-sereno-e-humanizador\/\" target=\"_blank\" rel=\"noopener noreferrer\">publicou\u00a0<\/a>a Nota Pastoral \u2018<a href=\"https:\/\/agencia.ecclesia.pt\/portal\/tag\/eutanasia-bioetica\/\" target=\"_blank\" rel=\"noopener noreferrer\">Eutan\u00e1sia<\/a>: o que est\u00e1 em causa? Contributos para um di\u00e1logo sereno e humanizador\u2019, na qual os bispos cat\u00f3licos afirmam que \u201cnunca \u00e9 absolutamente seguro que se respeita a vontade aut\u00eantica de uma pessoa que pede a eutan\u00e1sia\u201d.<\/p>\n<p style=\"text-align: justify;\"><em>PR<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Not\u00edcia e foto<\/p>\n","protected":false},"author":1,"featured_media":8180,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,146,10,13],"tags":[],"class_list":["post-8240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-acontece","category-letra-viva-valores-de-uma-cultura-que-cuida-e-nao-mata","category-noticias","category-olhares"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts\/8240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/comments?post=8240"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts\/8240\/revisions"}],"predecessor-version":[{"id":8241,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts\/8240\/revisions\/8241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/media\/8180"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/media?parent=8240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/categories?post=8240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/tags?post=8240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}