{"id":711,"date":"2017-05-10T10:32:18","date_gmt":"2017-05-10T10:32:18","guid":{"rendered":"http:\/\/diocese-aveiro.pt\/cultura\/?p=711"},"modified":"2017-05-19T13:58:41","modified_gmt":"2017-05-19T13:58:41","slug":"rosto-de-misericordia-padre-abraao-da-costa-lopes","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/cultura\/rosto-de-misericordia-padre-abraao-da-costa-lopes\/","title":{"rendered":"Rosto de miseric\u00f3rdia &#8211; Padre Abra\u00e3o da Costa Lopes"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>PADRE ABRA\u00c3O DA COSTA LOPES<\/strong><\/p>\n<p style=\"text-align: center;\">Georgino Rocha (Texto)<\/p>\n<p><strong>Padre Abra\u00e3o nasce na cidade de Braga, em 1925, onde vive e trabalha em v\u00e1rios sectores, designadamente como empregado de livraria, j\u00e1 adulto faz estudos nos semin\u00e1rios de Braga, de Aveiro e dos Olivais e vem a ser ordenado presb\u00edtero em 1966, por D. Manuel de Almeida Trindade, na Igreja paroquial de S\u00e3o Bernardo.<\/strong><\/p>\n<p><strong>Exerce o minist\u00e9rio pastoral na \u00abObra da Rua\u00bb, em Pa\u00e7o de Sousa (1966-1978) e, depois, como colaborador do p\u00e1roco de Vilarinho do Bairro, o P. Ant\u00f3nio Vidal. Daqui passa sucessivamente a ser p\u00e1roco de Amoreira da G\u00e2ndara, de Ancas, de Eixo, de Eirol, de Requeixo e da Gafanha da Boa-Hora. A partir de 1984, \u00e9 gerente da Livraria de Santa Joana, em Aveiro. Em setembro de 1999, por motivos de sa\u00fade, ausenta-se para Braga, onde tem familiares e amigos que lhe dedicam especial aten\u00e7\u00e3o. Habita actualmente na Casa Sacerdotal, S\u00e3o Martinho de Dume. Em Setembro pr\u00f3ximo, espera fazer 92 anos de idade.<\/strong><\/p>\n<p><strong>Porta aberta<\/strong><\/p>\n<p><strong>Na \u00faltima visita que lhe fiz, estranhei o facto de ter aberta a porta do quarto, sem que nada o justificasse. A funcion\u00e1ria atenta diz-me de imediato: \u201c\u00c9 ele que quer. Sempre foi assim\u201d. E a minha mem\u00f3ria voa para a \u00abObra da Rua\u00bb que consagra a pedagogia da \u201cporta aberta\u201d como processo de educa\u00e7\u00e3o. No\u00a0<em>site<\/em>\u00a0da Obra pode ler-se, entre os princ\u00edpios orientadores: Liberdade e espontaneidade: Ningu\u00e9m espere fazer homens de rapazes domados. &#8220;Porta sempre aberta&#8221;; responsabilidade: Em nossas casas todos e cada um tem a sua responsabilidade; virtudes humanas: Solidariedade, generosidade, camaradagem, amor ao pr\u00f3ximo &#8220;Os mais velhos cuidam dos mais novos&#8221;.<\/strong><\/p>\n<ol>\n<li><strong> Abra\u00e3o sintoniza com o processo educativo da \u00abObra\u00bb que lhe imprime um t\u00edpico estilo de vida na rela\u00e7\u00e3o pessoal e na ac\u00e7\u00e3o pastoral. Estilo efusivamente manifesto ao acolher o pequeno grupo de amigos que o visita e vai reconhecendo cada um. Sinal de um cora\u00e7\u00e3o aberto \u00e0 situa\u00e7\u00e3o em que se encontra e que valoriza admiravelmente, \u00e0 alegria de sentir as b\u00ean\u00e7\u00e3os de Deus em pequenas coisas e gestos atenciosos, simples, e, quando ajudado, \u00e0 mem\u00f3ria agradecida das pessoas que encontrou no exerc\u00edcio do minist\u00e9rio pastoral. O olhar irradia com nova intensidade ao contar que, nas suas muitas limita\u00e7\u00f5es, Deus lhe conserva a vis\u00e3o necess\u00e1ria para rezar a \u00abLiturgia das Horas\u00bb sem grande dificuldade, facto que considera um benef\u00edcio t\u00e3o grande como um milagre. \u00c9 que n\u00e3o consegue ler mais nada nem sequer o seu nome.<\/strong><\/li>\n<\/ol>\n<p><strong>Roteiro pastoral<\/strong><\/p>\n<p><strong>Juntos, fizemos um breve roteiro pastoral, peregrinando com a mem\u00f3ria pelos rostos de pessoas e locais onde havia trabalhado. Seguimos a lista acima indicada. \u00c0 medida que lembr\u00e1vamos algum nome e ele o reconhecia, batia palmas de alegria, o olhar revestia um novo brilho, os l\u00e1bios pronunciavam, ainda que a custo, palavras breves e expressivas. Uma vida de muitos anos concentrava-se naquele momento, a dist\u00e2ncia geogr\u00e1fica e hist\u00f3rica fazia-se proximidade contagiante, a experi\u00eancia adormecida brotava em gestos e monoss\u00edlabos de encanto, dando sentido \u00e0 doa\u00e7\u00e3o que sempre alimentou a sua entrega generosa. O P. Abra\u00e3o comunicava assim o seu autorretrato espiritual desenhado em tra\u00e7os significativos que deixam marcas na hist\u00f3ria de quem conviveu ou se cruzou nos seus caminhos.<\/strong><\/p>\n<p><strong>A t\u00edtulo de exemplo, destaca-se o testemunho da Irm\u00e3 Margarida Vieira, membro da comunidade das Irm\u00e3s de S. Jos\u00e9 de Cluny, na Gafanha da Boa Hora, que afirma ao rep\u00f3rter do \u00abCorreio do Vouga\u00bb a 03.08.1994 ser \u201c maravilhosa\u201d a experi\u00eancia em curso. Ela era a respons\u00e1vel pastoral da par\u00f3quia, enquanto o P. Abra\u00e3o mantinha as fun\u00e7\u00f5es de p\u00e1roco, indo de Aveiro onde geria a livraria Santa Joana. As outras quatro Irm\u00e3s animavam o servi\u00e7o socio-caritativo, acolhiam e acompanhavam jovens, reuniam com catequistas, faziam a prepara\u00e7\u00e3o de batismos e casamentos. \u201cEntre a Comunidade de Irm\u00e3s, os paroquianos e o padre Abra\u00e3o, est\u00e1 a haver uma absoluta colabora\u00e7\u00e3o e um entendimento que muito nos apraz registar. Ningu\u00e9m levanta barreiras a ningu\u00e9m. H\u00e1 uma harmoniosa colabora\u00e7\u00e3o\u201d \u2013 remata o Di\u00e1cono Daniel Rodrigues, rep\u00f3rter do Jornal diocesano.<\/strong><\/p>\n<p><strong>Vagueira, exemplo a seguir<\/strong><\/p>\n<p><strong>A preocupa\u00e7\u00e3o por estar onde as pessoas est\u00e3o e precisam de ajuda leva o P. Abra\u00e3o e um grupo de generosos volunt\u00e1rios a realizar durante anos uma experi\u00eancia inovadora: Erguer uma tenda gigante na praia da Vagueira para acolher veraneantes e celebrar a eucaristia. \u201cNo fim da celebra\u00e7\u00e3o, refere Daniel Rodrigues, convers\u00e1mos com ele, que, em linguagem discreta e simples, comentou-nos que \u00aba iniciativa nasceu de uma necessidade pastoral. A minha comunidade, nesta \u00e9poca, aumenta muito com os veraneantes e era necess\u00e1rio prestar-lhe o m\u00ednimo de assist\u00eancia religiosa, quer aqui na praia quer no parque de campismo ou na sede da Par\u00f3quia. E foi essa necessidade que me levou a tomar esta iniciativa, embora provis\u00f3ria, mas que julgo continuar at\u00e9 que, nesta praia, haja um templo\u00bb. E adianta: \u00aba Vagueira est\u00e1 a crescer de uma maneira inusitada e esta iniciativa serve tamb\u00e9m para se ir sensibilizando esta gente para a constitui\u00e7\u00e3o de um futuro n\u00facleo eclesial. A experi\u00eancia tornar-se-\u00e1 uma realidade com a constru\u00e7\u00e3o do templo, a que me referi\u00bb.<\/strong><\/p>\n<p><strong>Vagueira, exemplo a seguir. O II S\u00ednodo da Diocese, a decorrer, desperta a consci\u00eancia de muitos crist\u00e3os e mobiliza boas-vontades. A hora \u00e9 de ac\u00e7\u00e3o alicer\u00e7ada na ora\u00e7\u00e3o, de dar as m\u00e3os e sonhar o futuro j\u00e1 presente nas realidades interpelantes. Realidades de que se faz eco o hino sinodal: \u201cCaminhos novos se abrem, s\u00e3o caminhos de esperan\u00e7a\u201d\u2026\u201dUnidos em comunh\u00e3o, testemunho verdadeiro; despertos para a miss\u00e3o, somos Igreja de Aveiro\u201d.<\/strong><\/p>\n<p><strong>Livraria, local de encontro e espa\u00e7o de irradia\u00e7\u00e3o<\/strong><\/p>\n<p><strong>A arte de saber estar e \u201crentabilizar\u201d os recursos de uma livraria j\u00e1 vinham de longe. Mas acentua-se, a partir de 1984, ano em que come\u00e7a a gerir a livraria Santa Joana. Remodela os espa\u00e7os, renova o recheio, cria ambiente familiar que, pedagogicamente, encaminha a visita para os mostru\u00e1rio e as estantes onde se encontra o que lhe pode interessar. Amigo da beleza, gosta de evangelizar pela arte. Apreciador do valioso, ainda que antigo, procura valoriza-lo, expondo-o e comentando-o com sobriedade. Atento \u00e0s necessidades pastorais acompanha a vida das pessoas e, sobretudo, a das par\u00f3quias e, recheia a livraria, nas \u00e9pocas lit\u00fargicas marcantes.<\/strong><\/p>\n<p><strong>Uma das lembran\u00e7as que me\u00a0ocorre salientar, afirma o Di\u00e1cono Fernando Martins, tem a ver com \u201ca simplicidade do seu viver e das suas rela\u00e7\u00f5es com os frequentadores da livraria, n\u00e3o deixando passar a oportunidade de sugerir, delicadamente, esta ou aquela obra acabada de chegar. Dele, pois, recebi e aproveitei algumas propostas de compra\u201d.<\/strong><\/p>\n<p><strong>E o ent\u00e3o director do \u00abCorreio do Vouga\u00bb continua o seu testemunho: \u201cUm dia entrei na livraria e ele convidou-me para ir ao seu gabinete. Sentei-me a seu convite e mostrou-me, com um sorriso largo a iluminar o seu rosto um pouco seco, um livro antigo com edi\u00e7\u00e3o especial. Bonito e bem cuidado, o livro nem era de autor conhecido. Folheando-o, foi-me explicando a raz\u00e3o por que o havia comprado para seu regalo. Deu-me a entender que possu\u00eda mais obras raras\u201d.<\/strong><\/p>\n<p><strong>Envelhecimento feliz<\/strong><\/p>\n<p><strong>O modo af\u00e1vel de ser, o gosto pela beleza, o apre\u00e7o pela arte, sobretudo santoral, constituem um registo valioso do minist\u00e9rio do P. Abra\u00e3o. A vida gasta em doa\u00e7\u00e3o \u00e9 testemunho qualificado da grandeza do seu esp\u00edrito aberto aos sinais dos tempos. O saber retirar-se a tempo, aceitando a voz da natureza que alerta a consci\u00eancia para a proximidade de uma nova etapa da vida, \u00e9 prova de humilde lucidez e de corajosa decis\u00e3o.<\/strong><\/p>\n<p><strong>Agora est\u00e1 na Casa Sacerdotal de Braga. Sereno e feliz. Despojado do passado e aberto ao futuro de Deus, vivendo o instante do presente. Acarinhado por todos. Dando um belo testemunho de quem sabe envelhecer como t\u00e3o bem soube viver.<\/strong><\/p>\n<p><strong>Reproduzo versos de estrofes do poema\/ora\u00e7\u00e3o que se encontra \u00e0 entrada do corredor onde fica o seu quarto plurifuncional: \u201cAjuda-me, Senhor, a reconhecer as coisas boas da minha vida; d\u00e1-me for\u00e7a para aceitar as minhas limita\u00e7\u00f5es; faz, Senhor, que eu seja ainda \u00fatil para o mundo, com as minhas pequenas tarefas, mas sobretudo com o meu testemunho de paci\u00eancia e bondade, de serenidade, alegria e paz. Que os \u00faltimos anos da minha vida mortal sejam como um p\u00f4r do sol feliz: na ora\u00e7\u00e3o e na caridade, na compreens\u00e3o e na esperan\u00e7a. Que eu saiba envelhecer e morrer com a serenidade e a coragem com que Tu, Senhor, morreste na Cruz!\u201d.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PADRE ABRA\u00c3O DA<\/p>\n","protected":false},"author":1,"featured_media":712,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[46,13,50,15],"tags":[],"class_list":["post-711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autores","category-olhares","category-pe-georgino-rocha","category-rostos-de-misericorida"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts\/711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/comments?post=711"}],"version-history":[{"count":1,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts\/711\/revisions"}],"predecessor-version":[{"id":713,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts\/711\/revisions\/713"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/media\/712"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/media?parent=711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/categories?post=711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/tags?post=711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}