{"id":1079,"date":"2017-06-12T11:34:35","date_gmt":"2017-06-12T10:34:35","guid":{"rendered":"http:\/\/diocese-aveiro.pt\/cultura\/?p=1079"},"modified":"2017-06-12T11:34:35","modified_gmt":"2017-06-12T10:34:35","slug":"xi-domingo-do-tempo-comum-ano-a","status":"publish","type":"post","link":"https:\/\/diocese-aveiro.pt\/cultura\/xi-domingo-do-tempo-comum-ano-a\/","title":{"rendered":"XI Domingo do Tempo Comum (Ano A)"},"content":{"rendered":"<h5 style=\"text-align: center;\">Pe. Franclim Pacheco<\/h5>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1081 aligncenter\" src=\"https:\/\/diocese-aveiro.pt\/cultura\/wp-content\/uploads\/2017\/06\/Mt-9-36.jpg\" alt=\"\" width=\"551\" height=\"482\" srcset=\"https:\/\/diocese-aveiro.pt\/cultura\/wp-content\/uploads\/2017\/06\/Mt-9-36.jpg 551w, https:\/\/diocese-aveiro.pt\/cultura\/wp-content\/uploads\/2017\/06\/Mt-9-36-300x262.jpg 300w, https:\/\/diocese-aveiro.pt\/cultura\/wp-content\/uploads\/2017\/06\/Mt-9-36-343x300.jpg 343w\" sizes=\"auto, (max-width: 551px) 100vw, 551px\" \/><\/p>\n<p>Breve coment\u00e1rio<\/p>\n<p>Jesus, depois de ter proposto um programa novo e diferente da mentalidade do seu tempo (Mt 5), com a supera\u00e7\u00e3o da lei e da observ\u00e2ncia com as exig\u00eancias maiores do amor (Mt 6-7), depois de ter testemunhado o que tinha anunciado com gestos de liberta\u00e7\u00e3o (Mt 8-9), chama os seus disc\u00edpulos e envia-os \u00e0s multid\u00f5es dando-lhes os seus pr\u00f3prios poderes (Mt 10). A comunidade \u00e9 chamada a prolongar e a alargar a sua ac\u00e7\u00e3o libertadora, curadora, salv\u00edfica. O novo povo de Deus, sobre o fundamento dos doze ap\u00f3stolos, \u00e9 um povo sacerdotal, real e prof\u00e9tico, chamado a colaborar com Jesus.<\/p>\n<p>Atr\u00e1s, Jesus, ao ver a multid\u00f5es, sentou-se e ensinou-as. Agora, ao ver as multid\u00f5es sente compaix\u00e3o por elas, uma <em>compaix\u00e3o<\/em> que s\u00f3 Deus \u00e9 capaz de sentir pela humanidade. N\u00e3o h\u00e1 quem as ame e procure como um bom pastor.<\/p>\n<p>Jesus compara a miss\u00e3o a uma colheita. H\u00e1 tanta gente pronta a responder ao evangelho, tanta gente que espera uma palavra de vida, ma os mensageiros s\u00e3o poucos. A exorta\u00e7\u00e3o \u00e0 ora\u00e7\u00e3o est\u00e1 a significar que Deus est\u00e1 na origem da miss\u00e3o, \u00e9 respons\u00e1vel pela seara, a Ele devemos converter-nos com a ora\u00e7\u00e3o. Por isso chama os Doze e confia-lhes a miss\u00e3o.<\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>O n\u00famero 12 \u00e9 uma refer\u00eancia \u00e0s 12 tribos de Israel. Para anunciar a nova lei do novo Mois\u00e9s, \u00e9 preciso um novo povo que acolha a palavra do novo Mois\u00e9s (Jesus). A miss\u00e3o dos disc\u00edpulos \u00e9 posta em estreito paralelo com a miss\u00e3o de Jesus. A ideia dominante \u00e9 que o minist\u00e9rio dos ap\u00f3stolos \u00e9 o prolongamento do minist\u00e9rio de Jesus. \u00c9 dado aos disc\u00edpulos o mesmo \u00abpoder\u00bb que tinha Jesus (9,6-8; 7,29: 8,9)\u00a0 e a mesma ac\u00e7\u00e3o curadora (4,2; 9,35). N\u00e3o se trata de poder de chefia, de comando, mas do que \u00e9 necess\u00e1rio para a miss\u00e3o a eles confiada, para servir a humanidade.<\/p>\n<p>O termo \u00abap\u00f3stolo\u00bb apenas aqui \u00e9 usado por Mateus e com o sentido de \u00abenviados\u00bb. pelo que se pode entender como um convite dirigido a todo o novo Israel, atrav\u00e9s dos doze, as colunas do novo povo da nova lei, a lei do amor.<\/p>\n<p>As v\u00e1rias listas dos Doze (Mc 3.16-19; Lc 6, 13-16; Act 1,13), com pequenas varia\u00e7\u00f5es, t\u00eam sempre Pedro em primeiro lugar e Judas em \u00faltimo. \u00a0A diversidade: um publicano, um cananeu, um iscariotes que o trair\u00e1.\u00a0 Nem toda a gente parece, nem de boa posi\u00e7\u00e3o na sociedade nem instru\u00edda. O chamamento vem duma livre escolha de Jesus e n\u00e3o de m\u00e9ritos ou da import\u00e2ncia das pessoas, para que a fraqueza destes revele o poder de Deus.<\/p>\n<p>A limita\u00e7\u00e3o dos confins da miss\u00e3o (\u00abprimeiramente \u00e0s ovelhas perdidas da casa de Israel\u00bb) sublinha a prioridade a dar \u00e0 casa de Israel. Um interesse pelas \u00abovelhas perdidas\u00bb (Ez 34,1-16; Is 53,16) antes de mais, e a seguir pelas desconhecidas (os gentios). Mateus, crist\u00e3o judeu a escrever para crist\u00e3os judeus, coloca em evid\u00eancia o amor de Deus pelo povo de Israel. O mandato confiado aos ap\u00f3stolos \u00e9 muito importante: curar os doentes, ressuscitar os mortos, expulsar os dem\u00f3nios. Para Jesus nada \u00e9 imposs\u00edvel e tamb\u00e9m existem doentes e mortos espiritualmente n\u00e3o menos f\u00e1ceis de curar e fazer reviver do que os doentes e mortos fisicamente, e existem tamb\u00e9m possessos por ideologias e mentalidades destrutivas.<\/p>\n<p>Portanto, a miss\u00e3o \u00e9 feita de prega\u00e7\u00e3o e cura, an\u00fancio e promo\u00e7\u00e3o humana, vinda do Reino, juntamente com a luta pela justi\u00e7a e pela paz. Por isso, a miss\u00e3o n\u00e3o pode deixar de ser gratuita pois n\u00e3o pertence aos enviados. Assim se realiza o esp\u00edrito das bem-aventuran\u00e7as (Mt 6, 25-34).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pe. Franclim Pacheco<\/p>\n","protected":false},"author":1,"featured_media":1082,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[46,18,13,54],"tags":[],"class_list":["post-1079","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-autores","category-olhar-sobre-os-evangelhos","category-olhares","category-pe-julio-franclim-do-couto-e-pacheco","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts\/1079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/comments?post=1079"}],"version-history":[{"count":2,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts\/1079\/revisions"}],"predecessor-version":[{"id":1084,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/posts\/1079\/revisions\/1084"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/media\/1082"}],"wp:attachment":[{"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/media?parent=1079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/categories?post=1079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/diocese-aveiro.pt\/cultura\/wp-json\/wp\/v2\/tags?post=1079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}